{"id":121310,"date":"2024-03-06T20:20:37","date_gmt":"2024-03-07T01:20:37","guid":{"rendered":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/03\/PS_2024.3.7_COVID-19_00-03.png"},"modified":"2024-03-06T20:20:37","modified_gmt":"2024-03-07T01:20:37","slug":"ps_2024-3-7_covid-19_00-03-png","status":"inherit","type":"attachment","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/science\/2024\/03\/07\/how-americans-view-the-coronavirus-covid-19-vaccines-amid-declining-levels-of-concern\/ps_2024-3-7_covid-19_00-03-png\/","title":{"rendered":"Sharp decline in share of older Republicans who are up to date on COVID-19 vaccinations"},"author":581,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-121310","attachment","type-attachment","status-inherit","hentry"],"filename":"PS_2024.3.7_COVID-19_00-03.png","filesize":381557,"_embeds":[],"table_of_contents":[{"id":104052,"title":"How Americans View the Coronavirus, COVID-19 Vaccines Amid Declining Levels of Concern","slug":"how-americans-view-the-coronavirus-covid-19-vaccines-amid-declining-levels-of-concern","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/science\/2024\/03\/07\/how-americans-view-the-coronavirus-covid-19-vaccines-amid-declining-levels-of-concern\/","is_active":false},{"id":104053,"title":"Acknowledgments","slug":"acknowledgments-9-6","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/science\/2024\/03\/07\/acknowledgments-9-6\/","is_active":false},{"id":104062,"title":"Methodology","slug":"covid-declining-concern-methodology","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/science\/2024\/03\/07\/covid-declining-concern-methodology\/","is_active":false},{"id":104071,"title":"Appendix: Detailed chart and tables","slug":"covid-declining-concern-appendix","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/science\/2024\/03\/07\/covid-declining-concern-appendix\/","is_active":false}],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/03\/PS_2024.3.7_COVID-19_00-03.png'><img loading=\"lazy\" decoding=\"async\" width=\"218\" height=\"300\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/03\/PS_2024.3.7_COVID-19_00-03.png?w=218\" class=\"attachment-medium size-medium not-transparent\" alt=\"Chart shows Sharp decline in share of older Republicans who are up to date on COVID-19 vaccinations\" srcset=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/03\/PS_2024.3.7_COVID-19_00-03.png 840w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/03\/PS_2024.3.7_COVID-19_00-03.png?resize=218,300 218w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/03\/PS_2024.3.7_COVID-19_00-03.png?resize=768,1055 768w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/03\/PS_2024.3.7_COVID-19_00-03.png?resize=745,1024 745w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/03\/PS_2024.3.7_COVID-19_00-03.png?resize=295,405 295w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/03\/PS_2024.3.7_COVID-19_00-03.png?resize=200,275 200w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/03\/PS_2024.3.7_COVID-19_00-03.png?resize=260,357 260w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/03\/PS_2024.3.7_COVID-19_00-03.png?resize=310,426 310w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/03\/PS_2024.3.7_COVID-19_00-03.png?resize=420,577 420w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/03\/PS_2024.3.7_COVID-19_00-03.png?resize=640,879 640w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/03\/PS_2024.3.7_COVID-19_00-03.png?resize=740,1017 740w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/03\/PS_2024.3.7_COVID-19_00-03.png?resize=160,220 160w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/03\/PS_2024.3.7_COVID-19_00-03.png?resize=320,440 320w\" sizes=\"auto, (max-width: 218px) 100vw, 218px\" data-has-transparency=\"false\" data-dominant-color=\"f5f4f4\" style=\"--dominant-color: #f5f4f4;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Chart shows Sharp decline in share of older Republicans who are up to date on COVID-19 vaccinations","media_type":"image","mime_type":"image\/png","media_details":{"width":840,"height":1154,"file":"2024\/03\/PS_2024.3.7_COVID-19_00-03.png","filesize":381557,"sizes":{"thumbnail":{"file":"PS_2024.3.7_COVID-19_00-03.png?resize=150,150","width":150,"height":150,"filesize":381557,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/03\/PS_2024.3.7_COVID-19_00-03.png?w=150&h=150&crop=1"},"medium":{"file":"PS_2024.3.7_COVID-19_00-03.png?resize=218,300","width":218,"height":300,"filesize":381557,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/03\/PS_2024.3.7_COVID-19_00-03.png?w=218"},"medium_large":{"file":"PS_2024.3.7_COVID-19_00-03.png?resize=768,1055","width":768,"height":1055,"filesize":381557,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/03\/PS_2024.3.7_COVID-19_00-03.png?w=640"},"large":{"file":"PS_2024.3.7_COVID-19_00-03.png?resize=745,1024","width":745,"height":1024,"filesize":381557,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/03\/PS_2024.3.7_COVID-19_00-03.png?w=640"},"A1":{"file":"PS_2024.3.7_COVID-19_00-03.png?resize=564,317","width":564,"height":317,"filesize":381557,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/03\/PS_2024.3.7_COVID-19_00-03.png?w=564&h=317&crop=1"},"A1-HIDPI":{"file":"PS_2024.3.7_COVID-19_00-03.png?resize=840,634","width":840,"height":634,"filesize":381557,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/03\/PS_2024.3.7_COVID-19_00-03.png?w=840&h=634&crop=1"},"A1-SMALL":{"file":"PS_2024.3.7_COVID-19_00-03.png?resize=690,388","width":690,"height":388,"filesize":381557,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/03\/PS_2024.3.7_COVID-19_00-03.png?w=690&h=388&crop=1"},"A1-SMALL-HIDPI":{"file":"PS_2024.3.7_COVID-19_00-03.png?resize=840,776","width":840,"height":776,"filesize":381557,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/03\/PS_2024.3.7_COVID-19_00-03.png?w=840&h=776&crop=1"},"A2":{"file":"PS_2024.3.7_COVID-19_00-03.png?resize=268,151","width":268,"height":151,"filesize":381557,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/03\/PS_2024.3.7_COVID-19_00-03.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"PS_2024.3.7_COVID-19_00-03.png?resize=536,302","width":536,"height":302,"filesize":381557,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/03\/PS_2024.3.7_COVID-19_00-03.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"PS_2024.3.7_COVID-19_00-03.png?resize=690,388","width":690,"height":388,"filesize":381557,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/03\/PS_2024.3.7_COVID-19_00-03.png?w=690&h=388&crop=1"},"A2-SMALL-HIDPI":{"file":"PS_2024.3.7_COVID-19_00-03.png?resize=840,776","width":840,"height":776,"filesize":381557,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/03\/PS_2024.3.7_COVID-19_00-03.png?w=840&h=776&crop=1"},"A3":{"file":"PS_2024.3.7_COVID-19_00-03.png?resize=194,110","width":194,"height":110,"filesize":381557,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/03\/PS_2024.3.7_COVID-19_00-03.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"PS_2024.3.7_COVID-19_00-03.png?resize=388,220","width":388,"height":220,"filesize":381557,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/03\/PS_2024.3.7_COVID-19_00-03.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"PS_2024.3.7_COVID-19_00-03.png?resize=148,84","width":148,"height":84,"filesize":381557,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/03\/PS_2024.3.7_COVID-19_00-03.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"PS_2024.3.7_COVID-19_00-03.png?resize=296,168","width":296,"height":168,"filesize":381557,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/03\/PS_2024.3.7_COVID-19_00-03.png?w=296&h=168&crop=1"},"A4":{"file":"PS_2024.3.7_COVID-19_00-03.png?resize=268,151","width":268,"height":151,"filesize":381557,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/03\/PS_2024.3.7_COVID-19_00-03.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"PS_2024.3.7_COVID-19_00-03.png?resize=536,302","width":536,"height":302,"filesize":381557,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/03\/PS_2024.3.7_COVID-19_00-03.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"PS_2024.3.7_COVID-19_00-03.png?resize=690,388","width":690,"height":388,"filesize":381557,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/03\/PS_2024.3.7_COVID-19_00-03.png?w=690&h=388&crop=1"},"A4-SMALL-SHIDPI":{"file":"PS_2024.3.7_COVID-19_00-03.png?resize=840,776","width":840,"height":776,"filesize":381557,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/03\/PS_2024.3.7_COVID-19_00-03.png?w=840&h=776&crop=1"},"XL":{"file":"PS_2024.3.7_COVID-19_00-03.png?resize=720,405","width":720,"height":405,"filesize":381557,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/03\/PS_2024.3.7_COVID-19_00-03.png?w=720&h=405&crop=1"},"XL-HIDPI":{"file":"PS_2024.3.7_COVID-19_00-03.png?resize=840,810","width":840,"height":810,"filesize":381557,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/03\/PS_2024.3.7_COVID-19_00-03.png?w=840&h=810&crop=1"},"social":{"file":"PS_2024.3.7_COVID-19_00-03.png?resize=840,628","width":840,"height":628,"filesize":381557,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/03\/PS_2024.3.7_COVID-19_00-03.png?w=840&h=628&crop=1"},"chapter":{"file":"PS_2024.3.7_COVID-19_00-03.png?resize=295,405","width":295,"height":405,"filesize":381557,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/03\/PS_2024.3.7_COVID-19_00-03.png?w=295"},"200-wide":{"file":"PS_2024.3.7_COVID-19_00-03.png?resize=200,275","width":200,"height":275,"filesize":381557,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/03\/PS_2024.3.7_COVID-19_00-03.png?w=200"},"260-wide":{"file":"PS_2024.3.7_COVID-19_00-03.png?resize=260,357","width":260,"height":357,"filesize":381557,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/03\/PS_2024.3.7_COVID-19_00-03.png?w=260"},"310-wide":{"file":"PS_2024.3.7_COVID-19_00-03.png?resize=310,426","width":310,"height":426,"filesize":381557,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/03\/PS_2024.3.7_COVID-19_00-03.png?w=310"},"420-wide":{"file":"PS_2024.3.7_COVID-19_00-03.png?resize=420,577","width":420,"height":577,"filesize":381557,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/03\/PS_2024.3.7_COVID-19_00-03.png?w=420"},"640-wide":{"file":"PS_2024.3.7_COVID-19_00-03.png?resize=640,879","width":640,"height":879,"filesize":381557,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/03\/PS_2024.3.7_COVID-19_00-03.png?w=640"},"740-wide":{"file":"PS_2024.3.7_COVID-19_00-03.png?resize=740,1017","width":740,"height":1017,"filesize":381557,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/03\/PS_2024.3.7_COVID-19_00-03.png?w=740"},"75-square":{"file":"PS_2024.3.7_COVID-19_00-03.png?resize=75,75","width":75,"height":75,"filesize":381557,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/03\/PS_2024.3.7_COVID-19_00-03.png?w=75&h=75&crop=1"},"140-square":{"file":"PS_2024.3.7_COVID-19_00-03.png?resize=140,140","width":140,"height":140,"filesize":381557,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/03\/PS_2024.3.7_COVID-19_00-03.png?w=140&h=140&crop=1"},"260-square":{"file":"PS_2024.3.7_COVID-19_00-03.png?resize=260,260","width":260,"height":260,"filesize":381557,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/03\/PS_2024.3.7_COVID-19_00-03.png?w=260&h=260&crop=1"},"160-portrait":{"file":"PS_2024.3.7_COVID-19_00-03.png?resize=160,220","width":160,"height":220,"filesize":381557,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/03\/PS_2024.3.7_COVID-19_00-03.png?w=160"},"320-portrait":{"file":"PS_2024.3.7_COVID-19_00-03.png?resize=320,440","width":320,"height":440,"filesize":381557,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/03\/PS_2024.3.7_COVID-19_00-03.png?w=320"},"200-by-133":{"file":"PS_2024.3.7_COVID-19_00-03.png?resize=200,133","width":200,"height":133,"filesize":381557,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/03\/PS_2024.3.7_COVID-19_00-03.png?w=200&h=133&crop=1"},"740-by-416":{"file":"PS_2024.3.7_COVID-19_00-03.png?resize=740,416","width":740,"height":416,"filesize":381557,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/03\/PS_2024.3.7_COVID-19_00-03.png?w=740&h=416&crop=1"},"540-by-304":{"file":"PS_2024.3.7_COVID-19_00-03.png?resize=540,304","width":540,"height":304,"filesize":381557,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/03\/PS_2024.3.7_COVID-19_00-03.png?w=540&h=304&crop=1"},"full":{"file":"PS_2024.3.7_COVID-19_00-03.png","width":840,"height":1154,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/03\/PS_2024.3.7_COVID-19_00-03.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"f5f4f4","has_transparency":false},"post":104052,"source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/03\/PS_2024.3.7_COVID-19_00-03.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"Sharp decline in share of older Republicans who are up to date on COVID-19 vaccinations","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/121310","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/581"}],"replies":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=121310"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":104052,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts\/104052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}