{"id":11542,"date":"2022-07-19T15:01:36","date_gmt":"2022-07-19T20:01:36","guid":{"rendered":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/07\/FT_22.07.15_MultiGen_2.png"},"modified":"2022-07-19T15:01:36","modified_gmt":"2022-07-19T20:01:36","slug":"ft_22-07-15_multigen_2-png","status":"inherit","type":"attachment","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/short-reads\/2022\/07\/20\/young-adults-in-u-s-are-much-more-likely-than-50-years-ago-to-be-living-in-a-multigenerational-household\/ft_22-07-15_multigen_2-png\/","title":{"rendered":"A growing share of young adults are living in a parent\u2019s home \u2013 or in other multigenerational living arrangements"},"author":584,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-11542","attachment","type-attachment","status-inherit","hentry"],"filename":"FT_22.07.15_MultiGen_2.png","filesize":112081,"_embeds":[],"table_of_contents":[],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/07\/FT_22.07.15_MultiGen_2.png'><img loading=\"lazy\" decoding=\"async\" width=\"242\" height=\"300\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/07\/FT_22.07.15_MultiGen_2.png?w=242\" class=\"attachment-medium size-medium not-transparent\" alt=\"A line graph showing that a growing share of young adults are living in a parent\u2019s home \u2013 or in other multigenerational living arrangements\" srcset=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/07\/FT_22.07.15_MultiGen_2.png 620w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/07\/FT_22.07.15_MultiGen_2.png?resize=242,300 242w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/07\/FT_22.07.15_MultiGen_2.png?resize=326,405 326w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/07\/FT_22.07.15_MultiGen_2.png?resize=200,248 200w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/07\/FT_22.07.15_MultiGen_2.png?resize=260,323 260w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/07\/FT_22.07.15_MultiGen_2.png?resize=310,385 310w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/07\/FT_22.07.15_MultiGen_2.png?resize=420,522 420w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/07\/FT_22.07.15_MultiGen_2.png?resize=160,199 160w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/07\/FT_22.07.15_MultiGen_2.png?resize=320,397 320w\" sizes=\"auto, (max-width: 242px) 100vw, 242px\" data-has-transparency=\"false\" data-dominant-color=\"d7e5e1\" style=\"--dominant-color: #d7e5e1;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"A line graph showing that a growing share of young adults are living in a parent\u2019s home \u2013 or in other multigenerational living arrangements","media_type":"image","mime_type":"image\/png","media_details":{"width":620,"height":770,"file":"2022\/07\/FT_22.07.15_MultiGen_2.png","filesize":112081,"sizes":{"thumbnail":{"file":"FT_22.07.15_MultiGen_2.png?resize=150,150","width":150,"height":150,"filesize":112081,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/07\/FT_22.07.15_MultiGen_2.png?w=150&h=150&crop=1"},"medium":{"file":"FT_22.07.15_MultiGen_2.png?resize=242,300","width":242,"height":300,"filesize":112081,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/07\/FT_22.07.15_MultiGen_2.png?w=242"},"A1":{"file":"FT_22.07.15_MultiGen_2.png?resize=564,317","width":564,"height":317,"filesize":112081,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/07\/FT_22.07.15_MultiGen_2.png?w=564&h=317&crop=1"},"A1-HIDPI":{"file":"FT_22.07.15_MultiGen_2.png?resize=620,634","width":620,"height":634,"filesize":112081,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/07\/FT_22.07.15_MultiGen_2.png?w=620&h=634&crop=1"},"A1-SMALL":{"file":"FT_22.07.15_MultiGen_2.png?resize=620,388","width":620,"height":388,"filesize":112081,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/07\/FT_22.07.15_MultiGen_2.png?w=620&h=388&crop=1"},"A2":{"file":"FT_22.07.15_MultiGen_2.png?resize=268,151","width":268,"height":151,"filesize":112081,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/07\/FT_22.07.15_MultiGen_2.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"FT_22.07.15_MultiGen_2.png?resize=536,302","width":536,"height":302,"filesize":112081,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/07\/FT_22.07.15_MultiGen_2.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"FT_22.07.15_MultiGen_2.png?resize=620,388","width":620,"height":388,"filesize":112081,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/07\/FT_22.07.15_MultiGen_2.png?w=620&h=388&crop=1"},"A3":{"file":"FT_22.07.15_MultiGen_2.png?resize=194,110","width":194,"height":110,"filesize":112081,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/07\/FT_22.07.15_MultiGen_2.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"FT_22.07.15_MultiGen_2.png?resize=388,220","width":388,"height":220,"filesize":112081,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/07\/FT_22.07.15_MultiGen_2.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"FT_22.07.15_MultiGen_2.png?resize=148,84","width":148,"height":84,"filesize":112081,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/07\/FT_22.07.15_MultiGen_2.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"FT_22.07.15_MultiGen_2.png?resize=296,168","width":296,"height":168,"filesize":112081,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/07\/FT_22.07.15_MultiGen_2.png?w=296&h=168&crop=1"},"A4":{"file":"FT_22.07.15_MultiGen_2.png?resize=268,151","width":268,"height":151,"filesize":112081,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/07\/FT_22.07.15_MultiGen_2.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"FT_22.07.15_MultiGen_2.png?resize=536,302","width":536,"height":302,"filesize":112081,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/07\/FT_22.07.15_MultiGen_2.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"FT_22.07.15_MultiGen_2.png?resize=620,388","width":620,"height":388,"filesize":112081,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/07\/FT_22.07.15_MultiGen_2.png?w=620&h=388&crop=1"},"XL":{"file":"FT_22.07.15_MultiGen_2.png?resize=620,405","width":620,"height":405,"filesize":112081,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/07\/FT_22.07.15_MultiGen_2.png?w=620&h=405&crop=1"},"social":{"file":"FT_22.07.15_MultiGen_2.png?resize=620,628","width":620,"height":628,"filesize":112081,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/07\/FT_22.07.15_MultiGen_2.png?w=620&h=628&crop=1"},"chapter":{"file":"FT_22.07.15_MultiGen_2.png?resize=326,405","width":326,"height":405,"filesize":112081,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/07\/FT_22.07.15_MultiGen_2.png?w=326"},"200-wide":{"file":"FT_22.07.15_MultiGen_2.png?resize=200,248","width":200,"height":248,"filesize":112081,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/07\/FT_22.07.15_MultiGen_2.png?w=200"},"260-wide":{"file":"FT_22.07.15_MultiGen_2.png?resize=260,323","width":260,"height":323,"filesize":112081,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/07\/FT_22.07.15_MultiGen_2.png?w=260"},"310-wide":{"file":"FT_22.07.15_MultiGen_2.png?resize=310,385","width":310,"height":385,"filesize":112081,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/07\/FT_22.07.15_MultiGen_2.png?w=310"},"420-wide":{"file":"FT_22.07.15_MultiGen_2.png?resize=420,522","width":420,"height":522,"filesize":112081,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/07\/FT_22.07.15_MultiGen_2.png?w=420"},"75-square":{"file":"FT_22.07.15_MultiGen_2.png?resize=75,75","width":75,"height":75,"filesize":112081,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/07\/FT_22.07.15_MultiGen_2.png?w=75&h=75&crop=1"},"140-square":{"file":"FT_22.07.15_MultiGen_2.png?resize=140,140","width":140,"height":140,"filesize":112081,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/07\/FT_22.07.15_MultiGen_2.png?w=140&h=140&crop=1"},"260-square":{"file":"FT_22.07.15_MultiGen_2.png?resize=260,260","width":260,"height":260,"filesize":112081,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/07\/FT_22.07.15_MultiGen_2.png?w=260&h=260&crop=1"},"160-portrait":{"file":"FT_22.07.15_MultiGen_2.png?resize=160,199","width":160,"height":199,"filesize":112081,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/07\/FT_22.07.15_MultiGen_2.png?w=160"},"320-portrait":{"file":"FT_22.07.15_MultiGen_2.png?resize=320,397","width":320,"height":397,"filesize":112081,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/07\/FT_22.07.15_MultiGen_2.png?w=320"},"200-by-133":{"file":"FT_22.07.15_MultiGen_2.png?resize=200,133","width":200,"height":133,"filesize":112081,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/07\/FT_22.07.15_MultiGen_2.png?w=200&h=133&crop=1"},"740-by-416":{"file":"FT_22.07.15_MultiGen_2.png?resize=620,416","width":620,"height":416,"filesize":112081,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/07\/FT_22.07.15_MultiGen_2.png?w=620&h=416&crop=1"},"540-by-304":{"file":"FT_22.07.15_MultiGen_2.png?resize=540,304","width":540,"height":304,"filesize":112081,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/07\/FT_22.07.15_MultiGen_2.png?w=540&h=304&crop=1"},"full":{"file":"FT_22.07.15_MultiGen_2.png","width":620,"height":770,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/07\/FT_22.07.15_MultiGen_2.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"d7e5e1","has_transparency":false},"post":8417,"source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/07\/FT_22.07.15_MultiGen_2.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"A growing share of young adults are living in a parent\u2019s home \u2013 or in other multigenerational living arrangements","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/11542","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/584"}],"replies":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=11542"}],"wp:attached-to":[{"embeddable":true,"post_type":"short-read","id":8417,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/short-read\/8417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}