{"id":115053,"date":"2021-09-01T08:57:09","date_gmt":"2021-09-01T13:57:09","guid":{"rendered":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PI_2021.09.01_covid-and-tech_2-01a.png"},"modified":"2021-09-01T08:57:09","modified_gmt":"2021-09-01T13:57:09","slug":"pi_2021-09-01_covid-and-tech_2-01a-png","status":"inherit","type":"attachment","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/internet\/2021\/09\/01\/parents-their-children-and-school-during-the-pandemic\/pi_2021-09-01_covid-and-tech_2-01a-png\/","title":{"rendered":"Majority of parents whose children have learned online during the pandemic say their online instruction has gone well"},"author":377,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-115053","attachment","type-attachment","status-inherit","hentry"],"filename":"PI_2021.09.01_covid-and-tech_2-01a.png","filesize":349921,"_embeds":[],"table_of_contents":[],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PI_2021.09.01_covid-and-tech_2-01a.png'><img loading=\"lazy\" decoding=\"async\" width=\"224\" height=\"300\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PI_2021.09.01_covid-and-tech_2-01a.png?w=224\" class=\"attachment-medium size-medium not-transparent\" alt=\"Majority of parents whose children have learned online during the pandemic say their online instruction has gone well\" srcset=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PI_2021.09.01_covid-and-tech_2-01a.png 840w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PI_2021.09.01_covid-and-tech_2-01a.png?resize=224,300 224w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PI_2021.09.01_covid-and-tech_2-01a.png?resize=768,1029 768w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PI_2021.09.01_covid-and-tech_2-01a.png?resize=764,1024 764w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PI_2021.09.01_covid-and-tech_2-01a.png?resize=302,405 302w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PI_2021.09.01_covid-and-tech_2-01a.png?resize=200,268 200w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PI_2021.09.01_covid-and-tech_2-01a.png?resize=260,349 260w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PI_2021.09.01_covid-and-tech_2-01a.png?resize=310,416 310w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PI_2021.09.01_covid-and-tech_2-01a.png?resize=420,563 420w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PI_2021.09.01_covid-and-tech_2-01a.png?resize=640,858 640w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PI_2021.09.01_covid-and-tech_2-01a.png?resize=740,992 740w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PI_2021.09.01_covid-and-tech_2-01a.png?resize=160,214 160w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PI_2021.09.01_covid-and-tech_2-01a.png?resize=320,429 320w\" sizes=\"auto, (max-width: 224px) 100vw, 224px\" data-has-transparency=\"false\" data-dominant-color=\"e8eaec\" style=\"--dominant-color: #e8eaec;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Majority of parents whose children have learned online during the pandemic say their online instruction has gone well","media_type":"image","mime_type":"image\/png","media_details":{"width":840,"height":1126,"file":"2021\/09\/PI_2021.09.01_covid-and-tech_2-01a.png","filesize":349921,"sizes":{"thumbnail":{"file":"PI_2021.09.01_covid-and-tech_2-01a.png?resize=150,150","width":150,"height":150,"filesize":349921,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PI_2021.09.01_covid-and-tech_2-01a.png?w=150&h=150&crop=1"},"medium":{"file":"PI_2021.09.01_covid-and-tech_2-01a.png?resize=224,300","width":224,"height":300,"filesize":349921,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PI_2021.09.01_covid-and-tech_2-01a.png?w=224"},"medium_large":{"file":"PI_2021.09.01_covid-and-tech_2-01a.png?resize=768,1029","width":768,"height":1029,"filesize":349921,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PI_2021.09.01_covid-and-tech_2-01a.png?w=640"},"large":{"file":"PI_2021.09.01_covid-and-tech_2-01a.png?resize=764,1024","width":764,"height":1024,"filesize":349921,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PI_2021.09.01_covid-and-tech_2-01a.png?w=640"},"A1":{"file":"PI_2021.09.01_covid-and-tech_2-01a.png?resize=564,317","width":564,"height":317,"filesize":349921,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PI_2021.09.01_covid-and-tech_2-01a.png?w=564&h=317&crop=1"},"A1-HIDPI":{"file":"PI_2021.09.01_covid-and-tech_2-01a.png?resize=840,634","width":840,"height":634,"filesize":349921,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PI_2021.09.01_covid-and-tech_2-01a.png?w=840&h=634&crop=1"},"A1-SMALL":{"file":"PI_2021.09.01_covid-and-tech_2-01a.png?resize=690,388","width":690,"height":388,"filesize":349921,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PI_2021.09.01_covid-and-tech_2-01a.png?w=690&h=388&crop=1"},"A1-SMALL-HIDPI":{"file":"PI_2021.09.01_covid-and-tech_2-01a.png?resize=840,776","width":840,"height":776,"filesize":349921,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PI_2021.09.01_covid-and-tech_2-01a.png?w=840&h=776&crop=1"},"A2":{"file":"PI_2021.09.01_covid-and-tech_2-01a.png?resize=268,151","width":268,"height":151,"filesize":349921,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PI_2021.09.01_covid-and-tech_2-01a.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"PI_2021.09.01_covid-and-tech_2-01a.png?resize=536,302","width":536,"height":302,"filesize":349921,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PI_2021.09.01_covid-and-tech_2-01a.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"PI_2021.09.01_covid-and-tech_2-01a.png?resize=690,388","width":690,"height":388,"filesize":349921,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PI_2021.09.01_covid-and-tech_2-01a.png?w=690&h=388&crop=1"},"A2-SMALL-HIDPI":{"file":"PI_2021.09.01_covid-and-tech_2-01a.png?resize=840,776","width":840,"height":776,"filesize":349921,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PI_2021.09.01_covid-and-tech_2-01a.png?w=840&h=776&crop=1"},"A3":{"file":"PI_2021.09.01_covid-and-tech_2-01a.png?resize=194,110","width":194,"height":110,"filesize":349921,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PI_2021.09.01_covid-and-tech_2-01a.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"PI_2021.09.01_covid-and-tech_2-01a.png?resize=388,220","width":388,"height":220,"filesize":349921,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PI_2021.09.01_covid-and-tech_2-01a.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"PI_2021.09.01_covid-and-tech_2-01a.png?resize=148,84","width":148,"height":84,"filesize":349921,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PI_2021.09.01_covid-and-tech_2-01a.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"PI_2021.09.01_covid-and-tech_2-01a.png?resize=296,168","width":296,"height":168,"filesize":349921,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PI_2021.09.01_covid-and-tech_2-01a.png?w=296&h=168&crop=1"},"A4":{"file":"PI_2021.09.01_covid-and-tech_2-01a.png?resize=268,151","width":268,"height":151,"filesize":349921,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PI_2021.09.01_covid-and-tech_2-01a.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"PI_2021.09.01_covid-and-tech_2-01a.png?resize=536,302","width":536,"height":302,"filesize":349921,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PI_2021.09.01_covid-and-tech_2-01a.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"PI_2021.09.01_covid-and-tech_2-01a.png?resize=690,388","width":690,"height":388,"filesize":349921,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PI_2021.09.01_covid-and-tech_2-01a.png?w=690&h=388&crop=1"},"A4-SMALL-SHIDPI":{"file":"PI_2021.09.01_covid-and-tech_2-01a.png?resize=840,776","width":840,"height":776,"filesize":349921,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PI_2021.09.01_covid-and-tech_2-01a.png?w=840&h=776&crop=1"},"XL":{"file":"PI_2021.09.01_covid-and-tech_2-01a.png?resize=720,405","width":720,"height":405,"filesize":349921,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PI_2021.09.01_covid-and-tech_2-01a.png?w=720&h=405&crop=1"},"XL-HIDPI":{"file":"PI_2021.09.01_covid-and-tech_2-01a.png?resize=840,810","width":840,"height":810,"filesize":349921,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PI_2021.09.01_covid-and-tech_2-01a.png?w=840&h=810&crop=1"},"social":{"file":"PI_2021.09.01_covid-and-tech_2-01a.png?resize=840,628","width":840,"height":628,"filesize":349921,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PI_2021.09.01_covid-and-tech_2-01a.png?w=840&h=628&crop=1"},"chapter":{"file":"PI_2021.09.01_covid-and-tech_2-01a.png?resize=302,405","width":302,"height":405,"filesize":349921,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PI_2021.09.01_covid-and-tech_2-01a.png?w=302"},"200-wide":{"file":"PI_2021.09.01_covid-and-tech_2-01a.png?resize=200,268","width":200,"height":268,"filesize":349921,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PI_2021.09.01_covid-and-tech_2-01a.png?w=200"},"260-wide":{"file":"PI_2021.09.01_covid-and-tech_2-01a.png?resize=260,349","width":260,"height":349,"filesize":349921,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PI_2021.09.01_covid-and-tech_2-01a.png?w=260"},"310-wide":{"file":"PI_2021.09.01_covid-and-tech_2-01a.png?resize=310,416","width":310,"height":416,"filesize":349921,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PI_2021.09.01_covid-and-tech_2-01a.png?w=310"},"420-wide":{"file":"PI_2021.09.01_covid-and-tech_2-01a.png?resize=420,563","width":420,"height":563,"filesize":349921,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PI_2021.09.01_covid-and-tech_2-01a.png?w=420"},"640-wide":{"file":"PI_2021.09.01_covid-and-tech_2-01a.png?resize=640,858","width":640,"height":858,"filesize":349921,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PI_2021.09.01_covid-and-tech_2-01a.png?w=640"},"740-wide":{"file":"PI_2021.09.01_covid-and-tech_2-01a.png?resize=740,992","width":740,"height":992,"filesize":349921,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PI_2021.09.01_covid-and-tech_2-01a.png?w=740"},"75-square":{"file":"PI_2021.09.01_covid-and-tech_2-01a.png?resize=75,75","width":75,"height":75,"filesize":349921,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PI_2021.09.01_covid-and-tech_2-01a.png?w=75&h=75&crop=1"},"140-square":{"file":"PI_2021.09.01_covid-and-tech_2-01a.png?resize=140,140","width":140,"height":140,"filesize":349921,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PI_2021.09.01_covid-and-tech_2-01a.png?w=140&h=140&crop=1"},"260-square":{"file":"PI_2021.09.01_covid-and-tech_2-01a.png?resize=260,260","width":260,"height":260,"filesize":349921,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PI_2021.09.01_covid-and-tech_2-01a.png?w=260&h=260&crop=1"},"160-portrait":{"file":"PI_2021.09.01_covid-and-tech_2-01a.png?resize=160,214","width":160,"height":214,"filesize":349921,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PI_2021.09.01_covid-and-tech_2-01a.png?w=160"},"320-portrait":{"file":"PI_2021.09.01_covid-and-tech_2-01a.png?resize=320,429","width":320,"height":429,"filesize":349921,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PI_2021.09.01_covid-and-tech_2-01a.png?w=320"},"200-by-133":{"file":"PI_2021.09.01_covid-and-tech_2-01a.png?resize=200,133","width":200,"height":133,"filesize":349921,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PI_2021.09.01_covid-and-tech_2-01a.png?w=200&h=133&crop=1"},"740-by-416":{"file":"PI_2021.09.01_covid-and-tech_2-01a.png?resize=740,416","width":740,"height":416,"filesize":349921,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PI_2021.09.01_covid-and-tech_2-01a.png?w=740&h=416&crop=1"},"540-by-304":{"file":"PI_2021.09.01_covid-and-tech_2-01a.png?resize=540,304","width":540,"height":304,"filesize":349921,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PI_2021.09.01_covid-and-tech_2-01a.png?w=540&h=304&crop=1"},"full":{"file":"PI_2021.09.01_covid-and-tech_2-01a.png","width":840,"height":1126,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PI_2021.09.01_covid-and-tech_2-01a.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"e8eaec","has_transparency":false},"post":92966,"source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PI_2021.09.01_covid-and-tech_2-01a.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"Majority of parents whose children have learned online during the pandemic say their online instruction has gone well","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/115053","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/377"}],"replies":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=115053"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":92966,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts\/92966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}