{"id":115008,"date":"2022-03-14T14:23:47","date_gmt":"2022-03-14T19:23:47","guid":{"rendered":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/PS_2022.03.17_ai-he_05-06.png"},"modified":"2022-03-14T14:23:47","modified_gmt":"2022-03-14T19:23:47","slug":"ps_2022-03-17_ai-he_05-06-png","status":"inherit","type":"attachment","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/internet\/2022\/03\/17\/what-americans-think-about-possibilities-ahead-for-human-enhancement\/ps_2022-03-17_ai-he_05-06-png\/","title":{"rendered":"Americans say they would be more accepting of several physical and cognitive enhancements if there were limits on how they would work"},"author":581,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-115008","attachment","type-attachment","status-inherit","hentry"],"filename":"PS_2022.03.17_ai-he_05-06.png","filesize":148349,"_embeds":[],"table_of_contents":[],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/PS_2022.03.17_ai-he_05-06.png'><img loading=\"lazy\" decoding=\"async\" width=\"193\" height=\"300\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/PS_2022.03.17_ai-he_05-06.png?w=193\" class=\"attachment-medium size-medium not-transparent\" alt=\"Chart shows Americans say they would be more accepting of several physical and cognitive enhancements if there were limits on how they would work\" srcset=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/PS_2022.03.17_ai-he_05-06.png 840w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/PS_2022.03.17_ai-he_05-06.png?resize=193,300 193w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/PS_2022.03.17_ai-he_05-06.png?resize=768,1194 768w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/PS_2022.03.17_ai-he_05-06.png?resize=659,1024 659w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/PS_2022.03.17_ai-he_05-06.png?resize=260,404 260w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/PS_2022.03.17_ai-he_05-06.png?resize=200,311 200w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/PS_2022.03.17_ai-he_05-06.png?resize=310,482 310w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/PS_2022.03.17_ai-he_05-06.png?resize=420,653 420w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/PS_2022.03.17_ai-he_05-06.png?resize=640,995 640w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/PS_2022.03.17_ai-he_05-06.png?resize=740,1151 740w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/PS_2022.03.17_ai-he_05-06.png?resize=160,249 160w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/PS_2022.03.17_ai-he_05-06.png?resize=320,498 320w\" sizes=\"auto, (max-width: 193px) 100vw, 193px\" data-has-transparency=\"false\" data-dominant-color=\"dce1e2\" style=\"--dominant-color: #dce1e2;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Chart shows Americans say they would be more accepting of several physical and cognitive enhancements if there were limits on how they would work","media_type":"image","mime_type":"image\/png","media_details":{"width":840,"height":1306,"file":"2022\/03\/PS_2022.03.17_ai-he_05-06.png","filesize":148349,"sizes":{"thumbnail":{"file":"PS_2022.03.17_ai-he_05-06.png?resize=150,150","width":150,"height":150,"filesize":148349,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/PS_2022.03.17_ai-he_05-06.png?w=150&h=150&crop=1"},"medium":{"file":"PS_2022.03.17_ai-he_05-06.png?resize=193,300","width":193,"height":300,"filesize":148349,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/PS_2022.03.17_ai-he_05-06.png?w=193"},"medium_large":{"file":"PS_2022.03.17_ai-he_05-06.png?resize=768,1194","width":768,"height":1194,"filesize":148349,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/PS_2022.03.17_ai-he_05-06.png?w=640"},"large":{"file":"PS_2022.03.17_ai-he_05-06.png?resize=659,1024","width":659,"height":1024,"filesize":148349,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/PS_2022.03.17_ai-he_05-06.png?w=640"},"A1":{"file":"PS_2022.03.17_ai-he_05-06.png?resize=564,317","width":564,"height":317,"filesize":148349,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/PS_2022.03.17_ai-he_05-06.png?w=564&h=317&crop=1"},"A1-HIDPI":{"file":"PS_2022.03.17_ai-he_05-06.png?resize=840,634","width":840,"height":634,"filesize":148349,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/PS_2022.03.17_ai-he_05-06.png?w=840&h=634&crop=1"},"A1-SMALL":{"file":"PS_2022.03.17_ai-he_05-06.png?resize=690,388","width":690,"height":388,"filesize":148349,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/PS_2022.03.17_ai-he_05-06.png?w=690&h=388&crop=1"},"A1-SMALL-HIDPI":{"file":"PS_2022.03.17_ai-he_05-06.png?resize=840,776","width":840,"height":776,"filesize":148349,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/PS_2022.03.17_ai-he_05-06.png?w=840&h=776&crop=1"},"A2":{"file":"PS_2022.03.17_ai-he_05-06.png?resize=268,151","width":268,"height":151,"filesize":148349,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/PS_2022.03.17_ai-he_05-06.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"PS_2022.03.17_ai-he_05-06.png?resize=536,302","width":536,"height":302,"filesize":148349,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/PS_2022.03.17_ai-he_05-06.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"PS_2022.03.17_ai-he_05-06.png?resize=690,388","width":690,"height":388,"filesize":148349,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/PS_2022.03.17_ai-he_05-06.png?w=690&h=388&crop=1"},"A2-SMALL-HIDPI":{"file":"PS_2022.03.17_ai-he_05-06.png?resize=840,776","width":840,"height":776,"filesize":148349,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/PS_2022.03.17_ai-he_05-06.png?w=840&h=776&crop=1"},"A3":{"file":"PS_2022.03.17_ai-he_05-06.png?resize=194,110","width":194,"height":110,"filesize":148349,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/PS_2022.03.17_ai-he_05-06.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"PS_2022.03.17_ai-he_05-06.png?resize=388,220","width":388,"height":220,"filesize":148349,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/PS_2022.03.17_ai-he_05-06.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"PS_2022.03.17_ai-he_05-06.png?resize=148,84","width":148,"height":84,"filesize":148349,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/PS_2022.03.17_ai-he_05-06.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"PS_2022.03.17_ai-he_05-06.png?resize=296,168","width":296,"height":168,"filesize":148349,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/PS_2022.03.17_ai-he_05-06.png?w=296&h=168&crop=1"},"A4":{"file":"PS_2022.03.17_ai-he_05-06.png?resize=268,151","width":268,"height":151,"filesize":148349,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/PS_2022.03.17_ai-he_05-06.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"PS_2022.03.17_ai-he_05-06.png?resize=536,302","width":536,"height":302,"filesize":148349,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/PS_2022.03.17_ai-he_05-06.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"PS_2022.03.17_ai-he_05-06.png?resize=690,388","width":690,"height":388,"filesize":148349,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/PS_2022.03.17_ai-he_05-06.png?w=690&h=388&crop=1"},"A4-SMALL-SHIDPI":{"file":"PS_2022.03.17_ai-he_05-06.png?resize=840,776","width":840,"height":776,"filesize":148349,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/PS_2022.03.17_ai-he_05-06.png?w=840&h=776&crop=1"},"XL":{"file":"PS_2022.03.17_ai-he_05-06.png?resize=720,405","width":720,"height":405,"filesize":148349,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/PS_2022.03.17_ai-he_05-06.png?w=720&h=405&crop=1"},"XL-HIDPI":{"file":"PS_2022.03.17_ai-he_05-06.png?resize=840,810","width":840,"height":810,"filesize":148349,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/PS_2022.03.17_ai-he_05-06.png?w=840&h=810&crop=1"},"social":{"file":"PS_2022.03.17_ai-he_05-06.png?resize=840,628","width":840,"height":628,"filesize":148349,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/PS_2022.03.17_ai-he_05-06.png?w=840&h=628&crop=1"},"chapter":{"file":"PS_2022.03.17_ai-he_05-06.png?resize=260,405","width":260,"height":405,"filesize":148349,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/PS_2022.03.17_ai-he_05-06.png?w=260"},"200-wide":{"file":"PS_2022.03.17_ai-he_05-06.png?resize=200,311","width":200,"height":311,"filesize":148349,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/PS_2022.03.17_ai-he_05-06.png?w=200"},"260-wide":{"file":"PS_2022.03.17_ai-he_05-06.png?resize=260,404","width":260,"height":404,"filesize":148349,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/PS_2022.03.17_ai-he_05-06.png?w=260"},"310-wide":{"file":"PS_2022.03.17_ai-he_05-06.png?resize=310,482","width":310,"height":482,"filesize":148349,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/PS_2022.03.17_ai-he_05-06.png?w=310"},"420-wide":{"file":"PS_2022.03.17_ai-he_05-06.png?resize=420,653","width":420,"height":653,"filesize":148349,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/PS_2022.03.17_ai-he_05-06.png?w=420"},"640-wide":{"file":"PS_2022.03.17_ai-he_05-06.png?resize=640,995","width":640,"height":995,"filesize":148349,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/PS_2022.03.17_ai-he_05-06.png?w=640"},"740-wide":{"file":"PS_2022.03.17_ai-he_05-06.png?resize=740,1151","width":740,"height":1151,"filesize":148349,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/PS_2022.03.17_ai-he_05-06.png?w=740"},"75-square":{"file":"PS_2022.03.17_ai-he_05-06.png?resize=75,75","width":75,"height":75,"filesize":148349,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/PS_2022.03.17_ai-he_05-06.png?w=75&h=75&crop=1"},"140-square":{"file":"PS_2022.03.17_ai-he_05-06.png?resize=140,140","width":140,"height":140,"filesize":148349,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/PS_2022.03.17_ai-he_05-06.png?w=140&h=140&crop=1"},"260-square":{"file":"PS_2022.03.17_ai-he_05-06.png?resize=260,260","width":260,"height":260,"filesize":148349,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/PS_2022.03.17_ai-he_05-06.png?w=260&h=260&crop=1"},"160-portrait":{"file":"PS_2022.03.17_ai-he_05-06.png?resize=160,249","width":160,"height":249,"filesize":148349,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/PS_2022.03.17_ai-he_05-06.png?w=160"},"320-portrait":{"file":"PS_2022.03.17_ai-he_05-06.png?resize=320,498","width":320,"height":498,"filesize":148349,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/PS_2022.03.17_ai-he_05-06.png?w=320"},"200-by-133":{"file":"PS_2022.03.17_ai-he_05-06.png?resize=200,133","width":200,"height":133,"filesize":148349,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/PS_2022.03.17_ai-he_05-06.png?w=200&h=133&crop=1"},"740-by-416":{"file":"PS_2022.03.17_ai-he_05-06.png?resize=740,416","width":740,"height":416,"filesize":148349,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/PS_2022.03.17_ai-he_05-06.png?w=740&h=416&crop=1"},"540-by-304":{"file":"PS_2022.03.17_ai-he_05-06.png?resize=540,304","width":540,"height":304,"filesize":148349,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/PS_2022.03.17_ai-he_05-06.png?w=540&h=304&crop=1"},"full":{"file":"PS_2022.03.17_ai-he_05-06.png","width":840,"height":1306,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/PS_2022.03.17_ai-he_05-06.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"dce1e2","has_transparency":false},"post":92832,"source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/PS_2022.03.17_ai-he_05-06.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"Americans say they would be more accepting of several physical and cognitive enhancements if there were limits on how they would work","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/115008","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/581"}],"replies":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=115008"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":92832,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts\/92832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}