{"id":114470,"date":"2023-06-26T16:16:18","date_gmt":"2023-06-26T21:16:18","guid":{"rendered":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PI_2023.06.29_BLM-turns-10_1-03.png"},"modified":"2023-06-26T16:16:18","modified_gmt":"2023-06-26T21:16:18","slug":"pi_2023-06-29_blm-turns-10_1-03-png","status":"inherit","type":"attachment","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/data-labs\/2023\/06\/29\/ten-years-of-blacklivesmatter-on-twitter\/pi_2023-06-29_blm-turns-10_1-03-png\/","title":{"rendered":"Majority of #BlackLivesMatter tweets express support"},"author":377,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-114470","attachment","type-attachment","status-inherit","hentry"],"filename":"PI_2023.06.29_BLM-turns-10_1-03.png","filesize":99314,"_embeds":[],"table_of_contents":[],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PI_2023.06.29_BLM-turns-10_1-03.png'><img loading=\"lazy\" decoding=\"async\" width=\"269\" height=\"300\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PI_2023.06.29_BLM-turns-10_1-03.png?w=269\" class=\"attachment-medium size-medium not-transparent\" alt=\"A chart showing Majority of #BlackLivesMatter tweets express support\" srcset=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PI_2023.06.29_BLM-turns-10_1-03.png 840w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PI_2023.06.29_BLM-turns-10_1-03.png?resize=269,300 269w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PI_2023.06.29_BLM-turns-10_1-03.png?resize=768,856 768w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PI_2023.06.29_BLM-turns-10_1-03.png?resize=363,405 363w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PI_2023.06.29_BLM-turns-10_1-03.png?resize=200,223 200w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PI_2023.06.29_BLM-turns-10_1-03.png?resize=260,290 260w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PI_2023.06.29_BLM-turns-10_1-03.png?resize=310,345 310w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PI_2023.06.29_BLM-turns-10_1-03.png?resize=420,468 420w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PI_2023.06.29_BLM-turns-10_1-03.png?resize=640,713 640w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PI_2023.06.29_BLM-turns-10_1-03.png?resize=740,825 740w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PI_2023.06.29_BLM-turns-10_1-03.png?resize=160,178 160w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PI_2023.06.29_BLM-turns-10_1-03.png?resize=320,357 320w\" sizes=\"auto, (max-width: 269px) 100vw, 269px\" data-has-transparency=\"false\" data-dominant-color=\"ccd1b7\" style=\"--dominant-color: #ccd1b7;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"A chart showing Majority of #BlackLivesMatter tweets express support","media_type":"image","mime_type":"image\/png","media_details":{"width":840,"height":936,"file":"2023\/06\/PI_2023.06.29_BLM-turns-10_1-03.png","filesize":99314,"sizes":{"thumbnail":{"file":"PI_2023.06.29_BLM-turns-10_1-03.png?resize=150,150","width":150,"height":150,"filesize":99314,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PI_2023.06.29_BLM-turns-10_1-03.png?w=150&h=150&crop=1"},"medium":{"file":"PI_2023.06.29_BLM-turns-10_1-03.png?resize=269,300","width":269,"height":300,"filesize":99314,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PI_2023.06.29_BLM-turns-10_1-03.png?w=269"},"medium_large":{"file":"PI_2023.06.29_BLM-turns-10_1-03.png?resize=768,856","width":768,"height":856,"filesize":99314,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PI_2023.06.29_BLM-turns-10_1-03.png?w=640"},"A1":{"file":"PI_2023.06.29_BLM-turns-10_1-03.png?resize=564,317","width":564,"height":317,"filesize":99314,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PI_2023.06.29_BLM-turns-10_1-03.png?w=564&h=317&crop=1"},"A1-HIDPI":{"file":"PI_2023.06.29_BLM-turns-10_1-03.png?resize=840,634","width":840,"height":634,"filesize":99314,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PI_2023.06.29_BLM-turns-10_1-03.png?w=840&h=634&crop=1"},"A1-SMALL":{"file":"PI_2023.06.29_BLM-turns-10_1-03.png?resize=690,388","width":690,"height":388,"filesize":99314,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PI_2023.06.29_BLM-turns-10_1-03.png?w=690&h=388&crop=1"},"A1-SMALL-HIDPI":{"file":"PI_2023.06.29_BLM-turns-10_1-03.png?resize=840,776","width":840,"height":776,"filesize":99314,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PI_2023.06.29_BLM-turns-10_1-03.png?w=840&h=776&crop=1"},"A2":{"file":"PI_2023.06.29_BLM-turns-10_1-03.png?resize=268,151","width":268,"height":151,"filesize":99314,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PI_2023.06.29_BLM-turns-10_1-03.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"PI_2023.06.29_BLM-turns-10_1-03.png?resize=536,302","width":536,"height":302,"filesize":99314,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PI_2023.06.29_BLM-turns-10_1-03.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"PI_2023.06.29_BLM-turns-10_1-03.png?resize=690,388","width":690,"height":388,"filesize":99314,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PI_2023.06.29_BLM-turns-10_1-03.png?w=690&h=388&crop=1"},"A2-SMALL-HIDPI":{"file":"PI_2023.06.29_BLM-turns-10_1-03.png?resize=840,776","width":840,"height":776,"filesize":99314,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PI_2023.06.29_BLM-turns-10_1-03.png?w=840&h=776&crop=1"},"A3":{"file":"PI_2023.06.29_BLM-turns-10_1-03.png?resize=194,110","width":194,"height":110,"filesize":99314,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PI_2023.06.29_BLM-turns-10_1-03.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"PI_2023.06.29_BLM-turns-10_1-03.png?resize=388,220","width":388,"height":220,"filesize":99314,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PI_2023.06.29_BLM-turns-10_1-03.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"PI_2023.06.29_BLM-turns-10_1-03.png?resize=148,84","width":148,"height":84,"filesize":99314,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PI_2023.06.29_BLM-turns-10_1-03.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"PI_2023.06.29_BLM-turns-10_1-03.png?resize=296,168","width":296,"height":168,"filesize":99314,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PI_2023.06.29_BLM-turns-10_1-03.png?w=296&h=168&crop=1"},"A4":{"file":"PI_2023.06.29_BLM-turns-10_1-03.png?resize=268,151","width":268,"height":151,"filesize":99314,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PI_2023.06.29_BLM-turns-10_1-03.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"PI_2023.06.29_BLM-turns-10_1-03.png?resize=536,302","width":536,"height":302,"filesize":99314,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PI_2023.06.29_BLM-turns-10_1-03.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"PI_2023.06.29_BLM-turns-10_1-03.png?resize=690,388","width":690,"height":388,"filesize":99314,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PI_2023.06.29_BLM-turns-10_1-03.png?w=690&h=388&crop=1"},"A4-SMALL-SHIDPI":{"file":"PI_2023.06.29_BLM-turns-10_1-03.png?resize=840,776","width":840,"height":776,"filesize":99314,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PI_2023.06.29_BLM-turns-10_1-03.png?w=840&h=776&crop=1"},"XL":{"file":"PI_2023.06.29_BLM-turns-10_1-03.png?resize=720,405","width":720,"height":405,"filesize":99314,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PI_2023.06.29_BLM-turns-10_1-03.png?w=720&h=405&crop=1"},"XL-HIDPI":{"file":"PI_2023.06.29_BLM-turns-10_1-03.png?resize=840,810","width":840,"height":810,"filesize":99314,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PI_2023.06.29_BLM-turns-10_1-03.png?w=840&h=810&crop=1"},"social":{"file":"PI_2023.06.29_BLM-turns-10_1-03.png?resize=840,628","width":840,"height":628,"filesize":99314,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PI_2023.06.29_BLM-turns-10_1-03.png?w=840&h=628&crop=1"},"chapter":{"file":"PI_2023.06.29_BLM-turns-10_1-03.png?resize=363,405","width":363,"height":405,"filesize":99314,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PI_2023.06.29_BLM-turns-10_1-03.png?w=363"},"200-wide":{"file":"PI_2023.06.29_BLM-turns-10_1-03.png?resize=200,223","width":200,"height":223,"filesize":99314,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PI_2023.06.29_BLM-turns-10_1-03.png?w=200"},"260-wide":{"file":"PI_2023.06.29_BLM-turns-10_1-03.png?resize=260,290","width":260,"height":290,"filesize":99314,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PI_2023.06.29_BLM-turns-10_1-03.png?w=260"},"310-wide":{"file":"PI_2023.06.29_BLM-turns-10_1-03.png?resize=310,345","width":310,"height":345,"filesize":99314,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PI_2023.06.29_BLM-turns-10_1-03.png?w=310"},"420-wide":{"file":"PI_2023.06.29_BLM-turns-10_1-03.png?resize=420,468","width":420,"height":468,"filesize":99314,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PI_2023.06.29_BLM-turns-10_1-03.png?w=420"},"640-wide":{"file":"PI_2023.06.29_BLM-turns-10_1-03.png?resize=640,713","width":640,"height":713,"filesize":99314,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PI_2023.06.29_BLM-turns-10_1-03.png?w=640"},"740-wide":{"file":"PI_2023.06.29_BLM-turns-10_1-03.png?resize=740,825","width":740,"height":825,"filesize":99314,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PI_2023.06.29_BLM-turns-10_1-03.png?w=740"},"75-square":{"file":"PI_2023.06.29_BLM-turns-10_1-03.png?resize=75,75","width":75,"height":75,"filesize":99314,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PI_2023.06.29_BLM-turns-10_1-03.png?w=75&h=75&crop=1"},"140-square":{"file":"PI_2023.06.29_BLM-turns-10_1-03.png?resize=140,140","width":140,"height":140,"filesize":99314,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PI_2023.06.29_BLM-turns-10_1-03.png?w=140&h=140&crop=1"},"260-square":{"file":"PI_2023.06.29_BLM-turns-10_1-03.png?resize=260,260","width":260,"height":260,"filesize":99314,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PI_2023.06.29_BLM-turns-10_1-03.png?w=260&h=260&crop=1"},"160-portrait":{"file":"PI_2023.06.29_BLM-turns-10_1-03.png?resize=160,178","width":160,"height":178,"filesize":99314,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PI_2023.06.29_BLM-turns-10_1-03.png?w=160"},"320-portrait":{"file":"PI_2023.06.29_BLM-turns-10_1-03.png?resize=320,357","width":320,"height":357,"filesize":99314,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PI_2023.06.29_BLM-turns-10_1-03.png?w=320"},"200-by-133":{"file":"PI_2023.06.29_BLM-turns-10_1-03.png?resize=200,133","width":200,"height":133,"filesize":99314,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PI_2023.06.29_BLM-turns-10_1-03.png?w=200&h=133&crop=1"},"740-by-416":{"file":"PI_2023.06.29_BLM-turns-10_1-03.png?resize=740,416","width":740,"height":416,"filesize":99314,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PI_2023.06.29_BLM-turns-10_1-03.png?w=740&h=416&crop=1"},"540-by-304":{"file":"PI_2023.06.29_BLM-turns-10_1-03.png?resize=540,304","width":540,"height":304,"filesize":99314,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PI_2023.06.29_BLM-turns-10_1-03.png?w=540&h=304&crop=1"},"full":{"file":"PI_2023.06.29_BLM-turns-10_1-03.png","width":840,"height":936,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PI_2023.06.29_BLM-turns-10_1-03.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"ccd1b7","has_transparency":false},"post":92571,"source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PI_2023.06.29_BLM-turns-10_1-03.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"Majority of #BlackLivesMatter tweets express support","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/114470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/377"}],"replies":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=114470"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":92571,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts\/92571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}