{"id":108960,"date":"2020-03-11T10:28:41","date_gmt":"2020-03-11T15:28:41","guid":{"rendered":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/PJ_2020.03.10_PathwaysColumn8_feature.jpg"},"modified":"2020-03-11T10:28:41","modified_gmt":"2020-03-11T15:28:41","slug":"pj_2020-03-10_pathwayscolumn8_feature-jpg","status":"inherit","type":"attachment","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/journalism\/2020\/03\/11\/black-and-white-democrats-differ-in-their-media-diets-assessments-of-primaries\/pj_2020-03-10_pathwayscolumn8_feature-jpg\/","title":{"rendered":"A woman votes in the Democratic primaries at a Columbia, South Carolina, polling place on Feb. 29. (Matt McClain\/The Washington Post via Getty Images)"},"author":377,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-108960","attachment","type-attachment","status-inherit","hentry"],"filename":"PJ_2020.03.10_PathwaysColumn8_feature.jpg","filesize":52348,"_embeds":[],"table_of_contents":[],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/PJ_2020.03.10_PathwaysColumn8_feature-jpg.webp'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/PJ_2020.03.10_PathwaysColumn8_feature.jpg?w=300\" class=\"attachment-medium size-medium not-transparent\" alt=\"A woman votes in the Democratic primaries at a Columbia, South Carolina, polling place on Feb. 29. (Matt McClain\/The Washington Post via Getty Images)\" data-has-transparency=\"false\" data-dominant-color=\"bdb6b1\" style=\"--dominant-color: #bdb6b1;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"A woman votes in the Democratic primaries at a Columbia, South Carolina, polling place on Feb. 29. (Matt McClain\/The Washington Post via Getty Images)","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1280,"height":720,"file":"2020\/03\/PJ_2020.03.10_PathwaysColumn8_feature-jpg.webp","filesize":52348,"sizes":{"thumbnail":{"file":"PJ_2020.03.10_PathwaysColumn8_feature-jpg.webp?resize=150,150","width":150,"height":150,"filesize":52348,"mime_type":"image\/jpeg","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/PJ_2020.03.10_PathwaysColumn8_feature.jpg?w=150&h=150&crop=1"},"medium":{"file":"PJ_2020.03.10_PathwaysColumn8_feature-jpg.webp?resize=300,169","width":300,"height":169,"filesize":52348,"mime_type":"image\/jpeg","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/PJ_2020.03.10_PathwaysColumn8_feature.jpg?w=300"},"medium_large":{"file":"PJ_2020.03.10_PathwaysColumn8_feature-jpg.webp?resize=768,432","width":768,"height":432,"filesize":52348,"mime_type":"image\/jpeg","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/PJ_2020.03.10_PathwaysColumn8_feature.jpg?w=640"},"large":{"file":"PJ_2020.03.10_PathwaysColumn8_feature-jpg.webp?resize=1024,576","width":1024,"height":576,"filesize":52348,"mime_type":"image\/jpeg","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/PJ_2020.03.10_PathwaysColumn8_feature.jpg?w=640"},"A1":{"file":"PJ_2020.03.10_PathwaysColumn8_feature-jpg.webp?resize=564,317","width":564,"height":317,"filesize":52348,"mime_type":"image\/jpeg","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/PJ_2020.03.10_PathwaysColumn8_feature.jpg?w=564&h=317&crop=1"},"A1-HIDPI":{"file":"PJ_2020.03.10_PathwaysColumn8_feature-jpg.webp?resize=1128,634","width":1128,"height":634,"filesize":52348,"mime_type":"image\/jpeg","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/PJ_2020.03.10_PathwaysColumn8_feature.jpg?w=1128&h=634&crop=1"},"A1-SMALL":{"file":"PJ_2020.03.10_PathwaysColumn8_feature-jpg.webp?resize=690,388","width":690,"height":388,"filesize":52348,"mime_type":"image\/jpeg","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/PJ_2020.03.10_PathwaysColumn8_feature.jpg?w=690&h=388&crop=1"},"A2":{"file":"PJ_2020.03.10_PathwaysColumn8_feature-jpg.webp?resize=268,151","width":268,"height":151,"filesize":52348,"mime_type":"image\/jpeg","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/PJ_2020.03.10_PathwaysColumn8_feature.jpg?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"PJ_2020.03.10_PathwaysColumn8_feature-jpg.webp?resize=536,302","width":536,"height":302,"filesize":52348,"mime_type":"image\/jpeg","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/PJ_2020.03.10_PathwaysColumn8_feature.jpg?w=536&h=302&crop=1"},"A2-SMALL":{"file":"PJ_2020.03.10_PathwaysColumn8_feature-jpg.webp?resize=690,388","width":690,"height":388,"filesize":52348,"mime_type":"image\/jpeg","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/PJ_2020.03.10_PathwaysColumn8_feature.jpg?w=690&h=388&crop=1"},"A3":{"file":"PJ_2020.03.10_PathwaysColumn8_feature-jpg.webp?resize=194,110","width":194,"height":110,"filesize":52348,"mime_type":"image\/jpeg","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/PJ_2020.03.10_PathwaysColumn8_feature.jpg?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"PJ_2020.03.10_PathwaysColumn8_feature-jpg.webp?resize=388,220","width":388,"height":220,"filesize":52348,"mime_type":"image\/jpeg","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/PJ_2020.03.10_PathwaysColumn8_feature.jpg?w=388&h=220&crop=1"},"A3-SMALL":{"file":"PJ_2020.03.10_PathwaysColumn8_feature-jpg.webp?resize=148,84","width":148,"height":84,"filesize":52348,"mime_type":"image\/jpeg","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/PJ_2020.03.10_PathwaysColumn8_feature.jpg?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"PJ_2020.03.10_PathwaysColumn8_feature-jpg.webp?resize=296,168","width":296,"height":168,"filesize":52348,"mime_type":"image\/jpeg","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/PJ_2020.03.10_PathwaysColumn8_feature.jpg?w=296&h=168&crop=1"},"A4":{"file":"PJ_2020.03.10_PathwaysColumn8_feature-jpg.webp?resize=268,151","width":268,"height":151,"filesize":52348,"mime_type":"image\/jpeg","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/PJ_2020.03.10_PathwaysColumn8_feature.jpg?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"PJ_2020.03.10_PathwaysColumn8_feature-jpg.webp?resize=536,302","width":536,"height":302,"filesize":52348,"mime_type":"image\/jpeg","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/PJ_2020.03.10_PathwaysColumn8_feature.jpg?w=536&h=302&crop=1"},"A4-SMALL":{"file":"PJ_2020.03.10_PathwaysColumn8_feature-jpg.webp?resize=690,388","width":690,"height":388,"filesize":52348,"mime_type":"image\/jpeg","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/PJ_2020.03.10_PathwaysColumn8_feature.jpg?w=690&h=388&crop=1"},"XL":{"file":"PJ_2020.03.10_PathwaysColumn8_feature-jpg.webp?resize=720,405","width":720,"height":405,"filesize":52348,"mime_type":"image\/jpeg","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/PJ_2020.03.10_PathwaysColumn8_feature.jpg?w=720&h=405&crop=1"},"social":{"file":"PJ_2020.03.10_PathwaysColumn8_feature-jpg.webp?resize=1200,628","width":1200,"height":628,"filesize":52348,"mime_type":"image\/jpeg","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/PJ_2020.03.10_PathwaysColumn8_feature.jpg?w=1200&h=628&crop=1"},"chapter":{"file":"PJ_2020.03.10_PathwaysColumn8_feature-jpg.webp?resize=720,405","width":720,"height":405,"filesize":52348,"mime_type":"image\/jpeg","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/PJ_2020.03.10_PathwaysColumn8_feature.jpg?w=720"},"200-wide":{"file":"PJ_2020.03.10_PathwaysColumn8_feature-jpg.webp?resize=200,113","width":200,"height":113,"filesize":52348,"mime_type":"image\/jpeg","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/PJ_2020.03.10_PathwaysColumn8_feature.jpg?w=200"},"260-wide":{"file":"PJ_2020.03.10_PathwaysColumn8_feature-jpg.webp?resize=260,146","width":260,"height":146,"filesize":52348,"mime_type":"image\/jpeg","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/PJ_2020.03.10_PathwaysColumn8_feature.jpg?w=260"},"310-wide":{"file":"PJ_2020.03.10_PathwaysColumn8_feature-jpg.webp?resize=310,174","width":310,"height":174,"filesize":52348,"mime_type":"image\/jpeg","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/PJ_2020.03.10_PathwaysColumn8_feature.jpg?w=310"},"420-wide":{"file":"PJ_2020.03.10_PathwaysColumn8_feature-jpg.webp?resize=420,236","width":420,"height":236,"filesize":52348,"mime_type":"image\/jpeg","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/PJ_2020.03.10_PathwaysColumn8_feature.jpg?w=420"},"640-wide":{"file":"PJ_2020.03.10_PathwaysColumn8_feature-jpg.webp?resize=640,360","width":640,"height":360,"filesize":52348,"mime_type":"image\/jpeg","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/PJ_2020.03.10_PathwaysColumn8_feature.jpg?w=640"},"740-wide":{"file":"PJ_2020.03.10_PathwaysColumn8_feature-jpg.webp?resize=740,416","width":740,"height":416,"filesize":52348,"mime_type":"image\/jpeg","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/PJ_2020.03.10_PathwaysColumn8_feature.jpg?w=740"},"75-square":{"file":"PJ_2020.03.10_PathwaysColumn8_feature-jpg.webp?resize=75,75","width":75,"height":75,"filesize":52348,"mime_type":"image\/jpeg","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/PJ_2020.03.10_PathwaysColumn8_feature.jpg?w=75&h=75&crop=1"},"140-square":{"file":"PJ_2020.03.10_PathwaysColumn8_feature-jpg.webp?resize=140,140","width":140,"height":140,"filesize":52348,"mime_type":"image\/jpeg","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/PJ_2020.03.10_PathwaysColumn8_feature.jpg?w=140&h=140&crop=1"},"260-square":{"file":"PJ_2020.03.10_PathwaysColumn8_feature-jpg.webp?resize=260,260","width":260,"height":260,"filesize":52348,"mime_type":"image\/jpeg","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/PJ_2020.03.10_PathwaysColumn8_feature.jpg?w=260&h=260&crop=1"},"160-portrait":{"file":"PJ_2020.03.10_PathwaysColumn8_feature-jpg.webp?resize=160,90","width":160,"height":90,"filesize":52348,"mime_type":"image\/jpeg","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/PJ_2020.03.10_PathwaysColumn8_feature.jpg?w=160"},"320-portrait":{"file":"PJ_2020.03.10_PathwaysColumn8_feature-jpg.webp?resize=320,180","width":320,"height":180,"filesize":52348,"mime_type":"image\/jpeg","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/PJ_2020.03.10_PathwaysColumn8_feature.jpg?w=320"},"200-by-133":{"file":"PJ_2020.03.10_PathwaysColumn8_feature-jpg.webp?resize=200,133","width":200,"height":133,"filesize":52348,"mime_type":"image\/jpeg","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/PJ_2020.03.10_PathwaysColumn8_feature.jpg?w=200&h=133&crop=1"},"740-by-416":{"file":"PJ_2020.03.10_PathwaysColumn8_feature-jpg.webp?resize=740,416","width":740,"height":416,"filesize":52348,"mime_type":"image\/jpeg","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/PJ_2020.03.10_PathwaysColumn8_feature.jpg?w=740&h=416&crop=1"},"540-by-304":{"file":"PJ_2020.03.10_PathwaysColumn8_feature-jpg.webp?resize=540,304","width":540,"height":304,"filesize":52348,"mime_type":"image\/jpeg","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/PJ_2020.03.10_PathwaysColumn8_feature.jpg?w=540&h=304&crop=1"},"full":{"file":"PJ_2020.03.10_PathwaysColumn8_feature.jpg","width":1200,"height":675,"mime_type":"image\/jpeg","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/PJ_2020.03.10_PathwaysColumn8_feature.jpg"}},"image_meta":{"aperture":"4.5","credit":"The Washington Post via Getty Im","camera":"NIKON D5","caption":"COLUMBIA, SC - FEBRUARY 29: Claudia Craft votes at polling place on the day of the South Carolina primary on Saturday February 29, 2020 in Columbia, SC. (Photo by Matt McClain\/The Washington Post via Getty Images)","created_timestamp":"1582934400","copyright":"2020 The Washington Post","focal_length":"70","iso":"3200","shutter_speed":"0.0025","title":"South Carolina primary - Columbia, SC","orientation":"1","keywords":[]},"dominant_color":"bdb6b1","has_transparency":false,"sources":{"image\/webp":{"file":"PJ_2020.03.10_PathwaysColumn8_feature-jpg.webp","filesize":52348}},"original_image":"PJ_2020.03.10_PathwaysColumn8_feature.jpg"},"post":87824,"source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/PJ_2020.03.10_PathwaysColumn8_feature-jpg.webp","jetpack_videopress_guid":"","jetpack_videopress":{"title":"A woman votes in the Democratic primaries at a Columbia, South Carolina, polling place on Feb. 29. (Matt McClain\/The Washington Post via Getty Images)","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/108960","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/377"}],"replies":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=108960"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":87824,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts\/87824"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}