{"id":107869,"date":"2021-11-11T12:10:18","date_gmt":"2021-11-11T17:10:18","guid":{"rendered":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_2-01.png"},"modified":"2021-11-11T12:10:18","modified_gmt":"2021-11-11T17:10:18","slug":"pj_2021-11-15_twitter_2-01-png","status":"inherit","type":"attachment","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/journalism\/2021\/11\/15\/twitter-news-consumers-visit-site-more-often-than-other-twitter-users-but-still-go-there-most-for-entertainment\/pj_2021-11-15_twitter_2-01-png\/","title":{"rendered":"Twitter news consumers younger, more educated and more likely to be liberal Democrats than other users"},"author":377,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-107869","attachment","type-attachment","status-inherit","hentry"],"filename":"PJ_2021.11.15_twitter_2-01.png","filesize":298031,"_embeds":[],"table_of_contents":[],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_2-01.png'><img loading=\"lazy\" decoding=\"async\" width=\"242\" height=\"300\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_2-01.png?w=242\" class=\"attachment-medium size-medium not-transparent\" alt=\"Twitter news consumers younger, more educated and more likely to be liberal Democrats than other users\" srcset=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_2-01.png 840w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_2-01.png?resize=242,300 242w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_2-01.png?resize=768,951 768w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_2-01.png?resize=827,1024 827w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_2-01.png?resize=327,405 327w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_2-01.png?resize=200,248 200w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_2-01.png?resize=260,322 260w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_2-01.png?resize=310,384 310w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_2-01.png?resize=420,520 420w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_2-01.png?resize=640,792 640w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_2-01.png?resize=740,916 740w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_2-01.png?resize=160,198 160w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_2-01.png?resize=320,396 320w\" sizes=\"auto, (max-width: 242px) 100vw, 242px\" data-has-transparency=\"false\" data-dominant-color=\"e3dbdc\" style=\"--dominant-color: #e3dbdc;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Twitter news consumers younger, more educated and more likely to be liberal Democrats than other users","media_type":"image","mime_type":"image\/png","media_details":{"width":840,"height":1040,"file":"2021\/11\/PJ_2021.11.15_twitter_2-01.png","filesize":298031,"sizes":{"thumbnail":{"file":"PJ_2021.11.15_twitter_2-01.png?resize=150,150","width":150,"height":150,"filesize":298031,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_2-01.png?w=150&h=150&crop=1"},"medium":{"file":"PJ_2021.11.15_twitter_2-01.png?resize=242,300","width":242,"height":300,"filesize":298031,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_2-01.png?w=242"},"medium_large":{"file":"PJ_2021.11.15_twitter_2-01.png?resize=768,951","width":768,"height":951,"filesize":298031,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_2-01.png?w=640"},"large":{"file":"PJ_2021.11.15_twitter_2-01.png?resize=827,1024","width":827,"height":1024,"filesize":298031,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_2-01.png?w=640"},"A1":{"file":"PJ_2021.11.15_twitter_2-01.png?resize=564,317","width":564,"height":317,"filesize":298031,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_2-01.png?w=564&h=317&crop=1"},"A1-HIDPI":{"file":"PJ_2021.11.15_twitter_2-01.png?resize=840,634","width":840,"height":634,"filesize":298031,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_2-01.png?w=840&h=634&crop=1"},"A1-SMALL":{"file":"PJ_2021.11.15_twitter_2-01.png?resize=690,388","width":690,"height":388,"filesize":298031,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_2-01.png?w=690&h=388&crop=1"},"A1-SMALL-HIDPI":{"file":"PJ_2021.11.15_twitter_2-01.png?resize=840,776","width":840,"height":776,"filesize":298031,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_2-01.png?w=840&h=776&crop=1"},"A2":{"file":"PJ_2021.11.15_twitter_2-01.png?resize=268,151","width":268,"height":151,"filesize":298031,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_2-01.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"PJ_2021.11.15_twitter_2-01.png?resize=536,302","width":536,"height":302,"filesize":298031,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_2-01.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"PJ_2021.11.15_twitter_2-01.png?resize=690,388","width":690,"height":388,"filesize":298031,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_2-01.png?w=690&h=388&crop=1"},"A2-SMALL-HIDPI":{"file":"PJ_2021.11.15_twitter_2-01.png?resize=840,776","width":840,"height":776,"filesize":298031,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_2-01.png?w=840&h=776&crop=1"},"A3":{"file":"PJ_2021.11.15_twitter_2-01.png?resize=194,110","width":194,"height":110,"filesize":298031,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_2-01.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"PJ_2021.11.15_twitter_2-01.png?resize=388,220","width":388,"height":220,"filesize":298031,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_2-01.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"PJ_2021.11.15_twitter_2-01.png?resize=148,84","width":148,"height":84,"filesize":298031,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_2-01.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"PJ_2021.11.15_twitter_2-01.png?resize=296,168","width":296,"height":168,"filesize":298031,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_2-01.png?w=296&h=168&crop=1"},"A4":{"file":"PJ_2021.11.15_twitter_2-01.png?resize=268,151","width":268,"height":151,"filesize":298031,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_2-01.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"PJ_2021.11.15_twitter_2-01.png?resize=536,302","width":536,"height":302,"filesize":298031,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_2-01.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"PJ_2021.11.15_twitter_2-01.png?resize=690,388","width":690,"height":388,"filesize":298031,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_2-01.png?w=690&h=388&crop=1"},"A4-SMALL-SHIDPI":{"file":"PJ_2021.11.15_twitter_2-01.png?resize=840,776","width":840,"height":776,"filesize":298031,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_2-01.png?w=840&h=776&crop=1"},"XL":{"file":"PJ_2021.11.15_twitter_2-01.png?resize=720,405","width":720,"height":405,"filesize":298031,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_2-01.png?w=720&h=405&crop=1"},"XL-HIDPI":{"file":"PJ_2021.11.15_twitter_2-01.png?resize=840,810","width":840,"height":810,"filesize":298031,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_2-01.png?w=840&h=810&crop=1"},"social":{"file":"PJ_2021.11.15_twitter_2-01.png?resize=840,628","width":840,"height":628,"filesize":298031,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_2-01.png?w=840&h=628&crop=1"},"chapter":{"file":"PJ_2021.11.15_twitter_2-01.png?resize=327,405","width":327,"height":405,"filesize":298031,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_2-01.png?w=327"},"200-wide":{"file":"PJ_2021.11.15_twitter_2-01.png?resize=200,248","width":200,"height":248,"filesize":298031,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_2-01.png?w=200"},"260-wide":{"file":"PJ_2021.11.15_twitter_2-01.png?resize=260,322","width":260,"height":322,"filesize":298031,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_2-01.png?w=260"},"310-wide":{"file":"PJ_2021.11.15_twitter_2-01.png?resize=310,384","width":310,"height":384,"filesize":298031,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_2-01.png?w=310"},"420-wide":{"file":"PJ_2021.11.15_twitter_2-01.png?resize=420,520","width":420,"height":520,"filesize":298031,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_2-01.png?w=420"},"640-wide":{"file":"PJ_2021.11.15_twitter_2-01.png?resize=640,792","width":640,"height":792,"filesize":298031,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_2-01.png?w=640"},"740-wide":{"file":"PJ_2021.11.15_twitter_2-01.png?resize=740,916","width":740,"height":916,"filesize":298031,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_2-01.png?w=740"},"75-square":{"file":"PJ_2021.11.15_twitter_2-01.png?resize=75,75","width":75,"height":75,"filesize":298031,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_2-01.png?w=75&h=75&crop=1"},"140-square":{"file":"PJ_2021.11.15_twitter_2-01.png?resize=140,140","width":140,"height":140,"filesize":298031,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_2-01.png?w=140&h=140&crop=1"},"260-square":{"file":"PJ_2021.11.15_twitter_2-01.png?resize=260,260","width":260,"height":260,"filesize":298031,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_2-01.png?w=260&h=260&crop=1"},"160-portrait":{"file":"PJ_2021.11.15_twitter_2-01.png?resize=160,198","width":160,"height":198,"filesize":298031,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_2-01.png?w=160"},"320-portrait":{"file":"PJ_2021.11.15_twitter_2-01.png?resize=320,396","width":320,"height":396,"filesize":298031,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_2-01.png?w=320"},"200-by-133":{"file":"PJ_2021.11.15_twitter_2-01.png?resize=200,133","width":200,"height":133,"filesize":298031,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_2-01.png?w=200&h=133&crop=1"},"740-by-416":{"file":"PJ_2021.11.15_twitter_2-01.png?resize=740,416","width":740,"height":416,"filesize":298031,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_2-01.png?w=740&h=416&crop=1"},"540-by-304":{"file":"PJ_2021.11.15_twitter_2-01.png?resize=540,304","width":540,"height":304,"filesize":298031,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_2-01.png?w=540&h=304&crop=1"},"full":{"file":"PJ_2021.11.15_twitter_2-01.png","width":840,"height":1040,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_2-01.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"e3dbdc","has_transparency":false},"post":87599,"source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_2-01.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"Twitter news consumers younger, more educated and more likely to be liberal Democrats than other users","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/107869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/377"}],"replies":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=107869"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":87599,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts\/87599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}