{"id":107866,"date":"2021-11-11T12:45:38","date_gmt":"2021-11-11T17:45:38","guid":{"rendered":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_3-02a.png"},"modified":"2021-11-11T12:45:38","modified_gmt":"2021-11-11T17:45:38","slug":"pj_2021-11-15_twitter_3-02a-png","status":"inherit","type":"attachment","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/journalism\/2021\/11\/15\/among-twitter-news-consumers-democrats-tend-to-be-more-positive-about-getting-news-on-the-site\/pj_2021-11-15_twitter_3-02a-png\/","title":{"rendered":"Among Twitter news consumers, Republicans more likely to say they are worn out by the amount of news there than Democrats"},"author":377,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-107866","attachment","type-attachment","status-inherit","hentry"],"filename":"PJ_2021.11.15_twitter_3-02a.png","filesize":176199,"_embeds":[],"table_of_contents":[],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_3-02a.png'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"232\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_3-02a.png?w=300\" class=\"attachment-medium size-medium not-transparent\" alt=\"Among Twitter news consumers, Republicans more likely to say they are worn out by the amount of news there than Democrats\" srcset=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_3-02a.png 840w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_3-02a.png?resize=300,232 300w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_3-02a.png?resize=768,594 768w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_3-02a.png?resize=523,405 523w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_3-02a.png?resize=200,155 200w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_3-02a.png?resize=260,201 260w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_3-02a.png?resize=310,240 310w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_3-02a.png?resize=420,325 420w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_3-02a.png?resize=640,495 640w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_3-02a.png?resize=740,573 740w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_3-02a.png?resize=160,124 160w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_3-02a.png?resize=320,248 320w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-has-transparency=\"false\" data-dominant-color=\"e0dad6\" style=\"--dominant-color: #e0dad6;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Among Twitter news consumers, Republicans more likely to say they are worn out by the amount of news there than Democrats","media_type":"image","mime_type":"image\/png","media_details":{"width":840,"height":650,"file":"2021\/11\/PJ_2021.11.15_twitter_3-02a.png","filesize":176199,"sizes":{"thumbnail":{"file":"PJ_2021.11.15_twitter_3-02a.png?resize=150,150","width":150,"height":150,"filesize":176199,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_3-02a.png?w=150&h=150&crop=1"},"medium":{"file":"PJ_2021.11.15_twitter_3-02a.png?resize=300,232","width":300,"height":232,"filesize":176199,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_3-02a.png?w=300"},"medium_large":{"file":"PJ_2021.11.15_twitter_3-02a.png?resize=768,594","width":768,"height":594,"filesize":176199,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_3-02a.png?w=640"},"A1":{"file":"PJ_2021.11.15_twitter_3-02a.png?resize=564,317","width":564,"height":317,"filesize":176199,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_3-02a.png?w=564&h=317&crop=1"},"A1-HIDPI":{"file":"PJ_2021.11.15_twitter_3-02a.png?resize=840,634","width":840,"height":634,"filesize":176199,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_3-02a.png?w=840&h=634&crop=1"},"A1-SMALL":{"file":"PJ_2021.11.15_twitter_3-02a.png?resize=690,388","width":690,"height":388,"filesize":176199,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_3-02a.png?w=690&h=388&crop=1"},"A2":{"file":"PJ_2021.11.15_twitter_3-02a.png?resize=268,151","width":268,"height":151,"filesize":176199,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_3-02a.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"PJ_2021.11.15_twitter_3-02a.png?resize=536,302","width":536,"height":302,"filesize":176199,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_3-02a.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"PJ_2021.11.15_twitter_3-02a.png?resize=690,388","width":690,"height":388,"filesize":176199,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_3-02a.png?w=690&h=388&crop=1"},"A3":{"file":"PJ_2021.11.15_twitter_3-02a.png?resize=194,110","width":194,"height":110,"filesize":176199,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_3-02a.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"PJ_2021.11.15_twitter_3-02a.png?resize=388,220","width":388,"height":220,"filesize":176199,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_3-02a.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"PJ_2021.11.15_twitter_3-02a.png?resize=148,84","width":148,"height":84,"filesize":176199,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_3-02a.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"PJ_2021.11.15_twitter_3-02a.png?resize=296,168","width":296,"height":168,"filesize":176199,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_3-02a.png?w=296&h=168&crop=1"},"A4":{"file":"PJ_2021.11.15_twitter_3-02a.png?resize=268,151","width":268,"height":151,"filesize":176199,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_3-02a.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"PJ_2021.11.15_twitter_3-02a.png?resize=536,302","width":536,"height":302,"filesize":176199,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_3-02a.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"PJ_2021.11.15_twitter_3-02a.png?resize=690,388","width":690,"height":388,"filesize":176199,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_3-02a.png?w=690&h=388&crop=1"},"XL":{"file":"PJ_2021.11.15_twitter_3-02a.png?resize=720,405","width":720,"height":405,"filesize":176199,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_3-02a.png?w=720&h=405&crop=1"},"social":{"file":"PJ_2021.11.15_twitter_3-02a.png?resize=840,628","width":840,"height":628,"filesize":176199,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_3-02a.png?w=840&h=628&crop=1"},"chapter":{"file":"PJ_2021.11.15_twitter_3-02a.png?resize=523,405","width":523,"height":405,"filesize":176199,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_3-02a.png?w=523"},"200-wide":{"file":"PJ_2021.11.15_twitter_3-02a.png?resize=200,155","width":200,"height":155,"filesize":176199,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_3-02a.png?w=200"},"260-wide":{"file":"PJ_2021.11.15_twitter_3-02a.png?resize=260,201","width":260,"height":201,"filesize":176199,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_3-02a.png?w=260"},"310-wide":{"file":"PJ_2021.11.15_twitter_3-02a.png?resize=310,240","width":310,"height":240,"filesize":176199,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_3-02a.png?w=310"},"420-wide":{"file":"PJ_2021.11.15_twitter_3-02a.png?resize=420,325","width":420,"height":325,"filesize":176199,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_3-02a.png?w=420"},"640-wide":{"file":"PJ_2021.11.15_twitter_3-02a.png?resize=640,495","width":640,"height":495,"filesize":176199,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_3-02a.png?w=640"},"740-wide":{"file":"PJ_2021.11.15_twitter_3-02a.png?resize=740,573","width":740,"height":573,"filesize":176199,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_3-02a.png?w=740"},"75-square":{"file":"PJ_2021.11.15_twitter_3-02a.png?resize=75,75","width":75,"height":75,"filesize":176199,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_3-02a.png?w=75&h=75&crop=1"},"140-square":{"file":"PJ_2021.11.15_twitter_3-02a.png?resize=140,140","width":140,"height":140,"filesize":176199,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_3-02a.png?w=140&h=140&crop=1"},"260-square":{"file":"PJ_2021.11.15_twitter_3-02a.png?resize=260,260","width":260,"height":260,"filesize":176199,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_3-02a.png?w=260&h=260&crop=1"},"160-portrait":{"file":"PJ_2021.11.15_twitter_3-02a.png?resize=160,124","width":160,"height":124,"filesize":176199,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_3-02a.png?w=160"},"320-portrait":{"file":"PJ_2021.11.15_twitter_3-02a.png?resize=320,248","width":320,"height":248,"filesize":176199,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_3-02a.png?w=320"},"200-by-133":{"file":"PJ_2021.11.15_twitter_3-02a.png?resize=200,133","width":200,"height":133,"filesize":176199,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_3-02a.png?w=200&h=133&crop=1"},"740-by-416":{"file":"PJ_2021.11.15_twitter_3-02a.png?resize=740,416","width":740,"height":416,"filesize":176199,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_3-02a.png?w=740&h=416&crop=1"},"540-by-304":{"file":"PJ_2021.11.15_twitter_3-02a.png?resize=540,304","width":540,"height":304,"filesize":176199,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_3-02a.png?w=540&h=304&crop=1"},"full":{"file":"PJ_2021.11.15_twitter_3-02a.png","width":840,"height":650,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_3-02a.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"e0dad6","has_transparency":false},"post":87589,"source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/11\/PJ_2021.11.15_twitter_3-02a.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"Among Twitter news consumers, Republicans more likely to say they are worn out by the amount of news there than Democrats","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/107866","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/377"}],"replies":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=107866"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":87589,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts\/87589"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}