{"id":10665,"date":"2023-05-16T11:31:22","date_gmt":"2023-05-16T16:31:22","guid":{"rendered":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/sr_2023.05.17_elon_2.png"},"modified":"2023-05-16T11:31:22","modified_gmt":"2023-05-16T16:31:22","slug":"sr_2023-05-17_elon_2-png","status":"inherit","type":"attachment","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/short-reads\/2023\/05\/17\/how-us-adults-on-twitter-use-the-site-in-the-elon-musk-era\/sr_2023-05-17_elon_2-png\/","title":{"rendered":"Democrats on Twitter post a larger share of retweets, Republicans post a larger share of replies"},"author":658,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_protected":false,"_prc_workspace_id":0},"class_list":["post-10665","attachment","type-attachment","status-inherit","hentry"],"_embeds":[],"prc_checklist":{},"table_of_contents":[],"datacite_doi":"","jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/sr_2023.05.17_elon_2.png'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"217\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/sr_2023.05.17_elon_2.png?w=300\" class=\"attachment-medium size-medium not-transparent\" alt=\"Multiple bar charts that show Democrats on Twitter post a larger share of retweets, Republicans post a larger share of replies.\" srcset=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/sr_2023.05.17_elon_2.png 840w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/sr_2023.05.17_elon_2.png?resize=300,217 300w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/sr_2023.05.17_elon_2.png?resize=768,556 768w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/sr_2023.05.17_elon_2.png?resize=560,405 560w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/sr_2023.05.17_elon_2.png?resize=200,145 200w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/sr_2023.05.17_elon_2.png?resize=260,188 260w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/sr_2023.05.17_elon_2.png?resize=310,224 310w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/sr_2023.05.17_elon_2.png?resize=420,304 420w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/sr_2023.05.17_elon_2.png?resize=640,463 640w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/sr_2023.05.17_elon_2.png?resize=740,536 740w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/sr_2023.05.17_elon_2.png?resize=160,116 160w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/sr_2023.05.17_elon_2.png?resize=320,232 320w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-has-transparency=\"false\" data-dominant-color=\"eae6e2\" style=\"--dominant-color: #eae6e2;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Multiple bar charts that show Democrats on Twitter post a larger share of retweets, Republicans post a larger share of replies.","media_type":"image","mime_type":"image\/png","media_details":{"width":840,"height":608,"file":"2023\/05\/sr_2023.05.17_elon_2.png","filesize":98938,"sizes":{"thumbnail":{"file":"sr_2023.05.17_elon_2.png?resize=150,150","width":150,"height":150,"filesize":98938,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/sr_2023.05.17_elon_2.png?w=150&h=150&crop=1"},"medium":{"file":"sr_2023.05.17_elon_2.png?resize=300,217","width":300,"height":217,"filesize":98938,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/sr_2023.05.17_elon_2.png?w=300"},"medium_large":{"file":"sr_2023.05.17_elon_2.png?resize=768,556","width":768,"height":556,"filesize":98938,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/sr_2023.05.17_elon_2.png?w=640"},"A1":{"file":"sr_2023.05.17_elon_2.png?resize=564,317","width":564,"height":317,"filesize":98938,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/sr_2023.05.17_elon_2.png?w=564&h=317&crop=1"},"A1-SMALL":{"file":"sr_2023.05.17_elon_2.png?resize=690,388","width":690,"height":388,"filesize":98938,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/sr_2023.05.17_elon_2.png?w=690&h=388&crop=1"},"A2":{"file":"sr_2023.05.17_elon_2.png?resize=268,151","width":268,"height":151,"filesize":98938,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/sr_2023.05.17_elon_2.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"sr_2023.05.17_elon_2.png?resize=536,302","width":536,"height":302,"filesize":98938,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/sr_2023.05.17_elon_2.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"sr_2023.05.17_elon_2.png?resize=690,388","width":690,"height":388,"filesize":98938,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/sr_2023.05.17_elon_2.png?w=690&h=388&crop=1"},"A3":{"file":"sr_2023.05.17_elon_2.png?resize=194,110","width":194,"height":110,"filesize":98938,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/sr_2023.05.17_elon_2.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"sr_2023.05.17_elon_2.png?resize=388,220","width":388,"height":220,"filesize":98938,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/sr_2023.05.17_elon_2.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"sr_2023.05.17_elon_2.png?resize=148,84","width":148,"height":84,"filesize":98938,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/sr_2023.05.17_elon_2.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"sr_2023.05.17_elon_2.png?resize=296,168","width":296,"height":168,"filesize":98938,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/sr_2023.05.17_elon_2.png?w=296&h=168&crop=1"},"A4":{"file":"sr_2023.05.17_elon_2.png?resize=268,151","width":268,"height":151,"filesize":98938,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/sr_2023.05.17_elon_2.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"sr_2023.05.17_elon_2.png?resize=536,302","width":536,"height":302,"filesize":98938,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/sr_2023.05.17_elon_2.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"sr_2023.05.17_elon_2.png?resize=690,388","width":690,"height":388,"filesize":98938,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/sr_2023.05.17_elon_2.png?w=690&h=388&crop=1"},"XL":{"file":"sr_2023.05.17_elon_2.png?resize=720,405","width":720,"height":405,"filesize":98938,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/sr_2023.05.17_elon_2.png?w=720&h=405&crop=1"},"chapter":{"file":"sr_2023.05.17_elon_2.png?resize=560,405","width":560,"height":405,"filesize":98938,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/sr_2023.05.17_elon_2.png?w=560"},"200-wide":{"file":"sr_2023.05.17_elon_2.png?resize=200,145","width":200,"height":145,"filesize":98938,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/sr_2023.05.17_elon_2.png?w=200"},"260-wide":{"file":"sr_2023.05.17_elon_2.png?resize=260,188","width":260,"height":188,"filesize":98938,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/sr_2023.05.17_elon_2.png?w=260"},"310-wide":{"file":"sr_2023.05.17_elon_2.png?resize=310,224","width":310,"height":224,"filesize":98938,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/sr_2023.05.17_elon_2.png?w=310"},"420-wide":{"file":"sr_2023.05.17_elon_2.png?resize=420,304","width":420,"height":304,"filesize":98938,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/sr_2023.05.17_elon_2.png?w=420"},"640-wide":{"file":"sr_2023.05.17_elon_2.png?resize=640,463","width":640,"height":463,"filesize":98938,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/sr_2023.05.17_elon_2.png?w=640"},"740-wide":{"file":"sr_2023.05.17_elon_2.png?resize=740,536","width":740,"height":536,"filesize":98938,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/sr_2023.05.17_elon_2.png?w=740"},"75-square":{"file":"sr_2023.05.17_elon_2.png?resize=75,75","width":75,"height":75,"filesize":98938,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/sr_2023.05.17_elon_2.png?w=75&h=75&crop=1"},"140-square":{"file":"sr_2023.05.17_elon_2.png?resize=140,140","width":140,"height":140,"filesize":98938,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/sr_2023.05.17_elon_2.png?w=140&h=140&crop=1"},"260-square":{"file":"sr_2023.05.17_elon_2.png?resize=260,260","width":260,"height":260,"filesize":98938,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/sr_2023.05.17_elon_2.png?w=260&h=260&crop=1"},"160-portrait":{"file":"sr_2023.05.17_elon_2.png?resize=160,116","width":160,"height":116,"filesize":98938,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/sr_2023.05.17_elon_2.png?w=160"},"320-portrait":{"file":"sr_2023.05.17_elon_2.png?resize=320,232","width":320,"height":232,"filesize":98938,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/sr_2023.05.17_elon_2.png?w=320"},"200-by-133":{"file":"sr_2023.05.17_elon_2.png?resize=200,133","width":200,"height":133,"filesize":98938,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/sr_2023.05.17_elon_2.png?w=200&h=133&crop=1"},"740-by-416":{"file":"sr_2023.05.17_elon_2.png?resize=740,416","width":740,"height":416,"filesize":98938,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/sr_2023.05.17_elon_2.png?w=740&h=416&crop=1"},"540-by-304":{"file":"sr_2023.05.17_elon_2.png?resize=540,304","width":540,"height":304,"filesize":98938,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/sr_2023.05.17_elon_2.png?w=540&h=304&crop=1"},"full":{"file":"sr_2023.05.17_elon_2.png","width":840,"height":608,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/sr_2023.05.17_elon_2.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"eae6e2","has_transparency":false},"post":8102,"source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/sr_2023.05.17_elon_2.png","filename":"sr_2023.05.17_elon_2.png","filesize":98938,"_links":{"self":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/10665","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/658"}],"replies":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=10665"}],"wp:attached-to":[{"embeddable":true,"post_type":"short-read","id":8102,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/short-read\/8102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}