{"id":5916,"date":"2018-11-30T17:03:10","date_gmt":"2018-11-30T22:03:10","guid":{"rendered":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/?p=5916"},"modified":"2024-09-11T12:45:24","modified_gmt":"2024-09-11T16:45:24","slug":"scheda-informativa-atteggiamento-nei-confronti-dei-mezzi-di-informazione-e-tendenze-politiche-in-italia","status":"publish","type":"fact-sheet","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/global\/fact-sheet\/scheda-informativa-atteggiamento-nei-confronti-dei-mezzi-di-informazione-e-tendenze-politiche-in-italia\/","title":{"rendered":"Scheda informativa: atteggiamento nei confronti dei mezzi di informazione e tendenze politiche in Italia"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/global\/fact-sheet\/news-media-and-political-attitudes-in-italy\/\">inglese\/English<\/a><\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Di seguito sono riportati i risultati specifici in merito alle abitudini e all&#8217;atteggiamento nei confronti dei mezzi di informazione in Italia. I risultati derivano da un sondaggio del Pew Research Center sui mezzi di informazione e sulla politica in otto paesi dell&#8217;Europa occidentale condotto dal 30 ottobre al 20 dicembre 2017. Il sondaggio ha interessato cinque paesi del Nord (Danimarca, Germania, Paesi Bassi, Svezia e Regno Unito) e tre del Sud (Francia, Italia e Spagna).<\/p>\n\n\n\n<h2 data-is-section=\"true\" data-wp-context=\"{&quot;id&quot;:&quot;opinioni-sui-mezzi-di-informazione-in-italia&quot;}\" data-wp-interactive=\"{&quot;namespace&quot;:&quot;prc-block\\\/table-of-contents&quot;}\" class=\"wp-block-heading\" id=\"opinioni-sui-mezzi-di-informazione-in-italia\">Opinioni sui mezzi di informazione in Italia<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Il senso di importanza e di fiducia nei mezzi di informazione varia in modo considerevole in base al paese. In generale, vi \u00e8 una maggiore probabilit\u00e0 che gli adulti dei paesi dell&#8217;Europa del Nord (ad esempio, Svezia e Germania) affermino che i mezzi di informazione sono molto importanti e di avere fiducia in essi, mentre \u00e8 meno probabile che una tale affermazione provenga dagli abitanti di Francia e Italia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Solo un terzo circa degli adulti italiani (34%) considera i mezzi di informazione molto importanti per la societ\u00e0, mentre circa tre soggetti su dieci (29%) affermano di avere fiducia nei mezzi di informazione. Ci\u00f2 include solo un 3% di persone che hanno molta fiducia nei mezzi di informazione.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter\"><img data-dominant-color=\"dfd6c9\" data-has-transparency=\"false\" style=\"--dominant-color: #dfd6c9;\" decoding=\"async\" sizes=\"(max-width: 185px) 100vw, 185px\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/global\/wp-content\/uploads\/sites\/2\/2018\/11\/PJ_18.04.16_MediaPolitics_FactSheet_TrustImportance_Italy_translated.png\" alt=\"La minoranza degli adulti italiani ritiene che i mezzi di informazione siano molto importanti (circa tre persone su dieci hanno fiducia nei mezzi di informazione)\" class=\"wp-image-43019 not-transparent\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nella maggior parte dei paesi interessati dal sondaggio, vi \u00e8 una minore probabilit\u00e0 che le persone con idee populiste affermino che i mezzi di informazione sono importanti e di avere fiducia in essi rispetto alle persone che non hanno idee populiste. In generale, le differenze in questi atteggiamenti nei confronti dei mezzi di informazione sono piccole quando si effettua il confronto tra le persone che si posizionano a sinistra e a destra dello spettro ideologico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Queste differenze populiste emergono anche in Italia: il 26% delle persone con idee populiste afferma di avere fiducia nei mezzi di informazione rispetto al 34% delle persone che non hanno idee populiste. Riguardo alla domanda sull&#8217;importanza, il 29% delle persone con idee populiste afferma che i mezzi di informazione sono molto importanti per la societ\u00e0 in Italia rispetto al 43% di coloro che non hanno idee populiste.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter\"><img data-dominant-color=\"dcd0be\" data-has-transparency=\"false\" style=\"--dominant-color: #dcd0be;\" decoding=\"async\" sizes=\"(max-width: 292px) 100vw, 292px\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/global\/wp-content\/uploads\/sites\/2\/2018\/11\/PJ_18.04.16_MediaPolitics_FactSheet_ImportTrustByPopAndIdeol_Italy_translated.png\" alt=\"Divisioni in Italia tra coloro che hanno e non hanno idee populiste nell'atteggiamento nei confronti dei mezzi di informazione\" class=\"wp-image-43000 not-transparent\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 data-is-section=\"true\" data-wp-context=\"{&quot;id&quot;:&quot;principali-fonti-di-notizie-in-italia&quot;}\" data-wp-interactive=\"{&quot;namespace&quot;:&quot;prc-block\\\/table-of-contents&quot;}\" class=\"wp-block-heading\" id=\"principali-fonti-di-notizie-in-italia\">Principali fonti di notizie in Italia<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Per quanto riguarda le fonti di notizie alle quali le persone affermano di ricorrere con maggiore frequenza, le divisioni tra gli adulti con e senza tendenze populiste non sono cos\u00ec forti come quelle osservate per gli atteggiamenti nei confronti dei mezzi di informazione pi\u00f9 in generale. Nei paesi meridionali, tendono ad esservi divisioni maggiori nella preferenza sulle fonti di notizie principali tra le persone che si pongono a destra o a sinistra dello spettro ideologico rispetto a coloro con e senza idee populiste.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In Italia, coloro che hanno ideologie di destra e di sinistra si differenziano in maniera sostanziale per quanto riguarda la fonte di notizie a cui ricorrono maggiormente. Tra coloro che hanno ideologie di destra, Mediaset News \u00e8 la fonte di notizie principale maggiormente citata, mentre le persone di sinistra citano pi\u00f9 spesso Rai News.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter\"><img data-dominant-color=\"f2f3f3\" data-has-transparency=\"false\" style=\"--dominant-color: #f2f3f3;\" decoding=\"async\" sizes=\"(max-width: 293px) 100vw, 293px\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/global\/wp-content\/uploads\/sites\/2\/2018\/11\/PJ_18.04.16_MediaPolitics_FactSheet_MainSourceByIdeology_Italy_translated.png\" alt=\"Divisione ideologica tra gli italiani sulla principale fonte utilizzata per acquisire notizie\" class=\"wp-image-43007 not-transparent\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 data-is-section=\"true\" data-wp-context=\"{&quot;id&quot;:&quot;posizionamento-ideologico-dei-canali-di-informazione-destra-e-sinistra-secondo-gli-utenti&quot;}\" data-wp-interactive=\"{&quot;namespace&quot;:&quot;prc-block\\\/table-of-contents&quot;}\" class=\"wp-block-heading\" id=\"posizionamento-ideologico-dei-canali-di-informazione-destra-e-sinistra-secondo-gli-utenti\">Posizionamento ideologico dei canali di informazione (destra e sinistra) secondo gli utenti<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Per molti dei canali di informazione negli otto paesi, le persone che ne usano uno per acquisire le notizie tendono a pensare che sia pi\u00f9 vicino alla propria posizione ideologica di sinistra o di destra. In Italia, ci\u00f2 \u00e8 vero per i cinque canali di informazione presi in considerazione: Rai News, La7, La Repubblica, Corriere della Sera e Il Fatto Quotidiano. Per questi canali di informazione, gli utenti di destra o di sinistra tendono a posizionarli pi\u00f9 vicino alla propria ideologia. Per un canale di informazione, Mediaset News, gli utenti di destra e di sinistra generalmente concordano sul suo posizionamento. Il Giornale e Libero non sono inclusi in questa analisi poich\u00e9 non avevano un campione abbastanza grande di utenti di destra o di sinistra da analizzare.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter\"><img decoding=\"async\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/global\/wp-content\/uploads\/sites\/2\/2018\/11\/PJ_18.04.16_MediaPolitics_FactSheet_Mountains_Italy_translated.png\" alt=\"Posizionamento ideologico dei canali di informazione in Italia\" class=\"wp-image-43050\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In generale, il posizionamento di un canale da parte delle persone che non ne sono utenti tende a differire dall&#8217;effettivo posizionamento ideologico da parte del pubblico medio. Per ciascuno di questi canali di informazione presi in considerazione nel sondaggio, il pubblico medio (in base all&#8217;utilizzo autoriferito) tende a posizionarsi vicino al centro ideologico. Tuttavia, le persone che hanno sentito parlare di ciascun canale di informazione tendono a posizionarlo pi\u00f9 a destra o pi\u00f9 a sinistra del posizionamento ideologico effettivo del pubblico del canale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Questo \u00e8 il caso di alcuni canali in Italia (ma non tutti). Libero, ad esempio, ha un pubblico che si colloca al centro dello spettro sinistra-destra (3,6 su una scala da 0 a 6), ma quando viene chiesto di posizionare il canale di informazione sulla stessa scala sinistra-destra, le persone che hanno sentito parlare di Libero lo posizionano pi\u00f9 a destra (4,2). Gli altri canali invece mostrano una differenza minima: La7 ha un pubblico vicino al centro ideologico (3,2 su una scala da 0 a 6) e anche le persone che hanno sentito parlare di La7 lo posizionano vicino al centro dello spettro sinistra-destra (3,1).<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter\"><img data-dominant-color=\"e9e0cf\" data-has-transparency=\"false\" style=\"--dominant-color: #e9e0cf;\" decoding=\"async\" sizes=\"(max-width: 291px) 100vw, 291px\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/global\/wp-content\/uploads\/sites\/2\/2018\/11\/PJ_18.04.16_MediaPolitics_FactSheet_MeanOutletPlacement_Italian_translated.png\" alt=\"Gli italiani pensano che alcuni canali di informazione siano pi\u00f9 faziosi rispetto a quanto sia effettivamente il loro pubblico medio\" class=\"wp-image-43014 not-transparent\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 data-is-section=\"true\" data-wp-context=\"{&quot;id&quot;:&quot;fiducia-nei-canali-di-informazione&quot;}\" data-wp-interactive=\"{&quot;namespace&quot;:&quot;prc-block\\\/table-of-contents&quot;}\" class=\"wp-block-heading\" id=\"fiducia-nei-canali-di-informazione\">Fiducia nei canali di informazione<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">In sette degli otto paesi interessati dal sondaggio, il canale di informazione in cui si ha maggiore fiducia \u00e8 il servizio pubblico di ogni paese. In Italia, circa due terzi degli adulti (65%) affermano di avere fiducia nell&#8217;emittente pubblica Rai News.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter\"><img data-dominant-color=\"e2d7c3\" data-has-transparency=\"false\" style=\"--dominant-color: #e2d7c3;\" decoding=\"async\" sizes=\"(max-width: 292px) 100vw, 292px\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/global\/wp-content\/uploads\/sites\/2\/2018\/11\/PJ_18.04.16_MediaPolitics_FactSheet_OutletTrust_Italy-translated.png\" alt=\"In Italia, il pubblico mostra elevati livelli di fiducia nel servizio informativo pubblico\" class=\"wp-image-43029 not-transparent\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Come per la fiducia nei mezzi di informazione in generale, la fiducia negli specifici canali varia in base alle tendenze populiste, e coloro che hanno idee populiste esprimono livelli pi\u00f9 bassi di fiducia rispetto a coloro che non le hanno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In Italia, queste differenze emergono per alcuni canali. Ad esempio, vi \u00e8 una probabilit\u00e0 inferiore di 23 punti percentuali che le persone con tendenze populiste affermino di avere fiducia in La Repubblica rispetto a coloro che non hanno idee populiste. In Italia la fiducia si divide inoltre lungo lo spettro ideologico sinistra-destra. Vi \u00e8 una probabilit\u00e0 inferiore di 35 punti percentuali che le persone che si posizionano a sinistra della scala ideologica a 0-6 punti abbiano fiducia in Mediaset News rispetto alle persone di destra.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter\"><img data-dominant-color=\"e1d5c4\" data-has-transparency=\"false\" style=\"--dominant-color: #e1d5c4;\" decoding=\"async\" sizes=\"(max-width: 293px) 100vw, 293px\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/global\/wp-content\/uploads\/sites\/2\/2018\/11\/PJ_18.04.16_MediaPolitics_FactSheet_OutletTrustByPopAndIdeol_Italy-translated.png\" alt=\"In Italia, le persone con idee populiste hanno meno fiducia nei canali di informazione rispetto a coloro che non hanno tali idee\" class=\"wp-image-43036 not-transparent\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 data-is-section=\"true\" data-wp-context=\"{&quot;id&quot;:&quot;utilizzo-dei-social-media-e-opinioni&quot;}\" data-wp-interactive=\"{&quot;namespace&quot;:&quot;prc-block\\\/table-of-contents&quot;}\" class=\"wp-block-heading\" id=\"utilizzo-dei-social-media-e-opinioni\">Utilizzo dei social media e opinioni<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Molte persone dell&#8217;Europa occidentale acquisiscono le notizie attraverso i social media, con Facebook citato come piattaforma di notizie pi\u00f9 utilizzata.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La maggioranza degli adulti in Italia (64%) acquisisce notizie sui social media, e la met\u00e0 di essi acquisisce informazioni sui social media quotidianamente. Facebook \u00e8 il social network pi\u00f9 utilizzato per le notizie. In Italia vi \u00e8 una maggiore probabilit\u00e0 che i giovani (18-29 anni) acquisiscano quotidianamente le notizie sui social media rispetto alle persone di 50 anni o et\u00e0 superiore (74% contro 41%).<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter\"><img data-dominant-color=\"e3dacc\" data-has-transparency=\"false\" style=\"--dominant-color: #e3dacc;\" decoding=\"async\" sizes=\"(max-width: 293px) 100vw, 293px\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/global\/wp-content\/uploads\/sites\/2\/2018\/11\/PJ_18.04.16_MediaPolitics_FactSheet_SocialMediaUsage_Italy-translated.png\" alt=\"La maggioranza degli italiani acquisisce le notizie sui social media, principalmente da Facebook\" class=\"wp-image-43043 not-transparent\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Circa la met\u00e0 o pi\u00f9 dei consumatori di notizie sui social media degli otto paesi interessati dal sondaggio afferma di conoscere le fonti che vede sui social media. Tuttavia, minoranze considerevoli affermano di non prestare generalmente attenzione alla fonte di notizie che incontrano sui social media.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">I consumatori di notizie sui social media in Italia sono simili a quelli di altri paesi dell&#8217;Europa occidentale. Il 51% conosce le fonti di notizie che trova sui social media, ma circa un terzo (32%) non presta attenzione a queste fonti.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter\"><img data-dominant-color=\"eff0f1\" data-has-transparency=\"false\" style=\"--dominant-color: #eff0f1;\" decoding=\"async\" sizes=\"(max-width: 291px) 100vw, 291px\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/global\/wp-content\/uploads\/sites\/2\/2018\/11\/PJ_18.04.16_MediaPolitics_FactSheet_SocialMediaAttention_Italy-translated.png\" alt=\"Circa un terzo degli italiani che acquisisce le notizie sui social media non presta attenzione alle fonti di informazione\" class=\"wp-image-43057 not-transparent\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 data-is-section=\"true\" data-wp-context=\"{&quot;id&quot;:&quot;maggiori-informazioni&quot;}\" data-wp-interactive=\"{&quot;namespace&quot;:&quot;prc-block\\\/table-of-contents&quot;}\" class=\"wp-block-heading\" id=\"maggiori-informazioni\">Maggiori informazioni<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Questo testo \u00e8 stato tradotto dall\u2019inglese.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/journalism\/2018\/05\/16\/in-europa-occidentale-latteggiamento-del-pubblico-nei-confronti-dei-mezzi-di-informazione-e-piu-diviso-da-opinioni-populiste-che-da-ideologie-di-destra-o-di-sinistra\/\">Un riepilogo dei risultati<\/a> della relazione completa \u00e8 disponibile online in italiano. <a href=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/journalism\/2018\/05\/14\/in-western-europe-public-attitudes-toward-news-media-more-divided-by-populist-views-than-left-right-ideology\/\">La relazione completa<\/a> e <a href=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/journalism\/2018\/05\/14\/media-western-europe-methodology\/\">la metodologia<\/a> sono inoltre disponibili online in lingua inglese.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Per visualizzare queste informazioni online in italiano e in inglese, nonch\u00e9 i dati degli altri sette paesi dell&#8217;Europa occidentale inclusi nel sondaggio in inglese e nella lingua primaria di ciascun paese, visitare: <a href=\"https:\/\/pewrsr.ch\/ItalyNewsAttitudes\">https:\/\/pewrsr.ch\/ItalyNewsAttitudes<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Di seguito sono riportati i risultati specifici in merito alle abitudini e all&#8217;atteggiamento nei confronti dei mezzi di informazione in Italia. I risultati derivano da un sondaggio del Pew Research Center sui mezzi di informazione e sulla politica in otto paesi dell&#8217;Europa occidentale condotto dal 30 ottobre al 20 dicembre 2017.<\/p>\n","protected":false},"author":67,"featured_media":6379,"comment_status":"closed","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","datacite_doi":"","datacite_doi_citation":"","_prc_seo_qr_attachment_id":0,"displayBylines":true,"footnotes":"","prc_watchers":[],"_prc_fork_parent":0,"_prc_fork_status":"","_prc_active_fork":0},"categories":[],"bylines":[],"datasets":[],"_post_visibility":[],"formats":[464],"_fund_pool":[],"languages":[],"regions-countries":[],"research-teams":[525],"workflow-status":[],"collection":[2398],"class_list":["post-5916","fact-sheet","type-fact-sheet","status-publish","has-post-thumbnail","hentry","formats-fact-sheet","research-teams-global","collection-news-media-and-political-attitudes-in-western-europe"],"label":"Fact Sheet","post_parent":0,"word_count":1200,"canonical_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/global\/fact-sheet\/scheda-informativa-atteggiamento-nei-confronti-dei-mezzi-di-informazione-e-tendenze-politiche-in-italia\/","art_direction":{"A1":{"id":6379,"rawUrl":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2018\/05\/PJ_18.04.16_MediaPolitics_FactSheet_FeaturedImages_Italy.png","url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2018\/05\/PJ_18.04.16_MediaPolitics_FactSheet_FeaturedImages_Italy.png?w=564&h=317&crop=1","width":564,"height":317,"chartArt":false},"A2":{"id":6379,"rawUrl":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2018\/05\/PJ_18.04.16_MediaPolitics_FactSheet_FeaturedImages_Italy.png","url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2018\/05\/PJ_18.04.16_MediaPolitics_FactSheet_FeaturedImages_Italy.png?w=268&h=151&crop=1","width":268,"height":151,"chartArt":false},"A3":{"id":6379,"rawUrl":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2018\/05\/PJ_18.04.16_MediaPolitics_FactSheet_FeaturedImages_Italy.png","url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2018\/05\/PJ_18.04.16_MediaPolitics_FactSheet_FeaturedImages_Italy.png?w=194&h=110&crop=1","width":194,"height":110,"chartArt":false},"A4":{"id":6379,"rawUrl":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2018\/05\/PJ_18.04.16_MediaPolitics_FactSheet_FeaturedImages_Italy.png","url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2018\/05\/PJ_18.04.16_MediaPolitics_FactSheet_FeaturedImages_Italy.png?w=268&h=151&crop=1","width":268,"height":151,"chartArt":false},"XL":{"id":6379,"rawUrl":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2018\/05\/PJ_18.04.16_MediaPolitics_FactSheet_FeaturedImages_Italy.png","url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2018\/05\/PJ_18.04.16_MediaPolitics_FactSheet_FeaturedImages_Italy.png?w=640&h=320&crop=1","width":640,"height":320,"chartArt":false},"social":{"id":6379,"rawUrl":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2018\/05\/PJ_18.04.16_MediaPolitics_FactSheet_FeaturedImages_Italy.png","url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2018\/05\/PJ_18.04.16_MediaPolitics_FactSheet_FeaturedImages_Italy.png?w=640&h=320&crop=1","width":640,"height":320,"chartArt":false}},"_embeds":[],"prc_checklist":{},"watchChildPosts":false,"watchers":[],"table_of_contents":[],"datacite_doi":"","prc_seo_data":{"title":"Scheda informativa: atteggiamento nei confronti dei mezzi di informazione e tendenze politiche in Italia","description":"Di seguito sono riportati i risultati specifici in merito alle abitudini e all'atteggiamento nei confronti dei mezzi di informazione in Italia. I risultati derivano da un sondaggio del Pew Research Center sui mezzi di informazione e sulla politica in otto paesi dell'Europa occidentale condotto dal 30 ottobre al 20 dicembre 2017.","og_title":"Scheda informativa: atteggiamento nei confronti dei mezzi di informazione e tendenze politiche in Italia","og_description":"Di seguito sono riportati i risultati specifici in merito alle abitudini e all'atteggiamento nei confronti dei mezzi di informazione in Italia. I risultati derivano da un sondaggio del Pew Research Center sui mezzi di informazione e sulla politica in otto paesi dell'Europa occidentale condotto dal 30 ottobre al 20 dicembre 2017.","schema_type":"Article","noindex":false,"canonical_url":"","primary_terms":{"formats":464,"collection":2398},"custom_schema":[],"og_image":6379,"indexnow_submitted_at":null,"gsc_index_status":null},"jetpack_sharing_enabled":true,"bylinesOrdered":[],"acknowledgementsOrdered":[],"_links":{"self":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/fact-sheet\/5916","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/fact-sheet"}],"about":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/fact-sheet"}],"author":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/67"}],"replies":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=5916"}],"version-history":[{"count":3,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/fact-sheet\/5916\/revisions"}],"predecessor-version":[{"id":187066,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/fact-sheet\/5916\/revisions\/187066"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/6379"}],"wp:attachment":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media?parent=5916"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/categories?post=5916"},{"taxonomy":"bylines","embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/bylines?post=5916"},{"taxonomy":"datasets","embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/datasets?post=5916"},{"taxonomy":"_post_visibility","embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/_post_visibility?post=5916"},{"taxonomy":"formats","embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/formats?post=5916"},{"taxonomy":"_fund_pool","embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/_fund_pool?post=5916"},{"taxonomy":"languages","embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/languages?post=5916"},{"taxonomy":"regions-countries","embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/regions-countries?post=5916"},{"taxonomy":"research-teams","embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/research-teams?post=5916"},{"taxonomy":"workflow-status","embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/workflow-status?post=5916"},{"taxonomy":"collection","embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/collection?post=5916"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}